{"id":127411,"date":"2024-01-14T23:30:46","date_gmt":"2024-01-15T02:30:46","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=127411"},"modified":"2024-01-14T21:40:06","modified_gmt":"2024-01-15T00:40:06","slug":"piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/","title":{"rendered":"Piden que sujeto acusado de abuso sexual contra menor se vaya del sector"},"content":{"rendered":"<p><span style=\"color: #ff0000;\"><strong>Residentes de Villa El Descanso \u2018funan\u2019 a vecino:<\/strong><\/span><\/p>\n<p>\u2018\u00a1Que se vaya!\u2019 \u2018\u00a1Los ni\u00f1os no se tocan!\u2019, fueron algunas de las frases que pronunciaron los vecinos de calle Del \u00c1ngel en Villa El Descanso, frente al domicilio de un sujeto acusado de un presunto abuso sexual, quien qued\u00f3 en libertad, s\u00f3lo con medidas cautelares de menor intensidad.<\/p>\n<p>Estuvimos en esta actividad convocada por los propios vecinos este d\u00eda jueves a eso de las 21:00 horas, y pudimos conversar con una de las participantes, <strong>Dayam Pereira<\/strong>, quien explic\u00f3 que el motivo de esta convocatoria como le llamaron ellos, fue por <em>\u00abel abuso de una menor de 12 a\u00f1os, la cual la pareja ten\u00eda a su cuidado hace 8 meses, y el 23 de diciembre se dio a conocer la noticia de que el cuidador, en este caso la pareja de la due\u00f1a del inmueble, abus\u00f3 de la ni\u00f1a. Eso lo dijo su propia pareja, que ella cuando entr\u00f3 a la habitaci\u00f3n de la ni\u00f1a, vio al tipo encima de ella tocando sus partes \u00edntimas\u00bb,<\/em> se\u00f1ala.<\/p>\n<p>&#8211; <strong>\u00bfAh\u00ed lo denunci\u00f3?<\/strong><\/p>\n<p>&#8211; Claro, ella denunci\u00f3 el hecho y este tipo est\u00e1 en investigaci\u00f3n por 150 d\u00edas. La se\u00f1ora estuvo cuatro d\u00edas con la ni\u00f1a, la cual despu\u00e9s entreg\u00f3 y ahora est\u00e1 en internado en Los Andes por lo que sabemos los vecinos. El tema es que esta se\u00f1ora entreg\u00f3 a la ni\u00f1a y ahora este tipo, el abusador, est\u00e1 viviendo nuevamente con ella, por eso es la convocatoria de los vecinos.<\/p>\n<p>&#8211; <strong>\u00bfQu\u00e9 quieren ustedes, que se vaya?<\/strong><\/p>\n<p>&#8211; Queremos que \u00e9l se aleje de la villa, que se vaya, porque anteriormente ya ha habido abusos de parte de \u00e9l hacia otras vecinas, entonces queremos que \u00e9l se vaya.<\/p>\n<p>&#8211; <strong>\u00bfQu\u00e9 abusos ha habido?<\/strong><\/p>\n<p>&#8211; Provocaciones, palabras, insinuaciones; a\u00f1os atr\u00e1s abord\u00f3 a una ni\u00f1a toc\u00e1ndola, bes\u00e1ndola, la cual tuvo que irse de la villa por este hecho.<\/p>\n<p>&#8211; <strong>O sea la idea principal de esta convocatoria es para que \u00e9l se vaya de la Villa.<\/strong><\/p>\n<p>&#8211; Para que \u00e9l se vaya de la villa o que lo metan preso, as\u00ed de simple, porque es un abusador.<\/p>\n<p>&#8211; <strong>\u00bfQu\u00e9 pasa si \u00e9l no se va, ustedes van a seguir con este tipo de convocatoria?<\/strong><\/p>\n<p>&#8211; Vamos a seguir protestando hasta que este hombre ya no llegue m\u00e1s ac\u00e1.<\/p>\n<p>&#8211; <strong>\u00bfQu\u00e9 podemos decir de \u00e9l, una persona que se nota tranquila?<\/strong><\/p>\n<p>&#8211; O sea, s\u00ed, es una persona que siempre ronda el sector, tranquila si bien, pero cuando ve mujeres solas, el tipo las molesta con palabras, se les acerca, conversa entre otras cosas.<\/p>\n<p>&#8211; <strong>\u00bfEn qu\u00e9 trabaja?<\/strong><\/p>\n<p>&#8211; Yo no s\u00e9 en qu\u00e9 trabaja, s\u00ed s\u00e9 que tiene 66 a\u00f1os.<\/p>\n<p>Tambi\u00e9n conversamos con el presidente de la junta de vecinos, <strong>Marcelo Lara<\/strong>, quien dijo que ellos como junta vecinal escucharon a los residentes <em>\u00aben una reuni\u00f3n hasta las 20:00 horas de hoy d\u00eda <\/em>(jueves),<em> donde plantearon hacer esta actividad como vecinos, no como junta, sino que como vecinos que le han afectado lo que ha hecho este caballero. Hay varios acosos que ha hecho, m\u00e1s de 6-7 personas, pero no los han declarado ante Carabineros, entonces por no haber esas denuncias, la justicia no puede hacer nada, habi\u00e9ndose hecho una denuncia t\u00e9ngalo por hecho que lo tenemos tras las rejas\u00bb,<\/em> se\u00f1al\u00f3.<\/p>\n<p>El acusado es de iniciales <strong>H.M.<\/strong><\/p>\n<figure id=\"attachment_127412\" aria-describedby=\"caption-attachment-127412\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-127412\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-1-el-dscanso.jpg\" alt=\"Desde temprano comenzaron a reunirse los vecinos para manifestarse frente al domicilio del acusado.\" width=\"699\" height=\"369\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-1-el-dscanso.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-1-el-dscanso-300x158.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-1-el-dscanso-150x79.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-1-el-dscanso-696x367.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-127412\" class=\"wp-caption-text\">Desde temprano comenzaron a reunirse los vecinos para manifestarse frente al domicilio del acusado.<\/figcaption><\/figure>\n<figure id=\"attachment_127413\" aria-describedby=\"caption-attachment-127413\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-127413\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-2-el-descanso.jpg\" alt=\"Vecinos con pancartas exig\u00edan que se vaya acusado de abuso sexual contra una ni\u00f1a de 12 a\u00f1os que estaba al cuidado de \u00e9l y su pareja.\" width=\"700\" height=\"455\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-2-el-descanso.jpg 700w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-2-el-descanso-300x195.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-2-el-descanso-150x98.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-2-el-descanso-696x452.jpg 696w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-2-el-descanso-646x420.jpg 646w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-127413\" class=\"wp-caption-text\">Vecinos con pancartas exig\u00edan que se vaya acusado de abuso sexual contra una ni\u00f1a de 12 a\u00f1os que estaba al cuidado de \u00e9l y su pareja.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Residentes de Villa El Descanso \u2018funan\u2019 a vecino: \u2018\u00a1Que se vaya!\u2019 \u2018\u00a1Los ni\u00f1os no se tocan!\u2019, fueron algunas de las frases que pronunciaron los vecinos de calle Del \u00c1ngel en Villa El Descanso, frente al domicilio de un sujeto acusado de un presunto abuso sexual, quien qued\u00f3 en libertad, s\u00f3lo con medidas cautelares de menor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":127413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-127411","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-comunidad"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Piden que sujeto acusado de abuso sexual contra menor se vaya del sector - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piden que sujeto acusado de abuso sexual contra menor se vaya del sector - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Residentes de Villa El Descanso \u2018funan\u2019 a vecino: \u2018\u00a1Que se vaya!\u2019 \u2018\u00a1Los ni\u00f1os no se tocan!\u2019, fueron algunas de las frases que pronunciaron los vecinos de calle Del \u00c1ngel en Villa El Descanso, frente al domicilio de un sujeto acusado de un presunto abuso sexual, quien qued\u00f3 en libertad, s\u00f3lo con medidas cautelares de menor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-15T02:30:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-2-el-descanso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"455\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Piden que sujeto acusado de abuso sexual contra menor se vaya del sector\",\"datePublished\":\"2024-01-15T02:30:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\\\/\"},\"wordCount\":647,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Vecinos-2-el-descanso.jpg\",\"articleSection\":[\"Comunidad\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\\\/\",\"name\":\"Piden que sujeto acusado de abuso sexual contra menor se vaya del sector - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Vecinos-2-el-descanso.jpg\",\"datePublished\":\"2024-01-15T02:30:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Vecinos-2-el-descanso.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Vecinos-2-el-descanso.jpg\",\"width\":700,\"height\":455,\"caption\":\"Vecinos con pancartas exig\u00edan que se vaya acusado de abuso sexual contra una ni\u00f1a de 12 a\u00f1os que estaba al cuidado de \u00e9l y su pareja.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piden que sujeto acusado de abuso sexual contra menor se vaya del sector\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piden que sujeto acusado de abuso sexual contra menor se vaya del sector - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/","og_locale":"es_ES","og_type":"article","og_title":"Piden que sujeto acusado de abuso sexual contra menor se vaya del sector - Diario El Trabajo","og_description":"Residentes de Villa El Descanso \u2018funan\u2019 a vecino: \u2018\u00a1Que se vaya!\u2019 \u2018\u00a1Los ni\u00f1os no se tocan!\u2019, fueron algunas de las frases que pronunciaron los vecinos de calle Del \u00c1ngel en Villa El Descanso, frente al domicilio de un sujeto acusado de un presunto abuso sexual, quien qued\u00f3 en libertad, s\u00f3lo con medidas cautelares de menor [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2024-01-15T02:30:46+00:00","og_image":[{"width":700,"height":455,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-2-el-descanso.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Piden que sujeto acusado de abuso sexual contra menor se vaya del sector","datePublished":"2024-01-15T02:30:46+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/"},"wordCount":647,"commentCount":0,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-2-el-descanso.jpg","articleSection":["Comunidad"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/","url":"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/","name":"Piden que sujeto acusado de abuso sexual contra menor se vaya del sector - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-2-el-descanso.jpg","datePublished":"2024-01-15T02:30:46+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-2-el-descanso.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/Vecinos-2-el-descanso.jpg","width":700,"height":455,"caption":"Vecinos con pancartas exig\u00edan que se vaya acusado de abuso sexual contra una ni\u00f1a de 12 a\u00f1os que estaba al cuidado de \u00e9l y su pareja."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/piden-que-sujeto-acusado-de-abuso-sexual-contra-menor-se-vaya-del-sector\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Piden que sujeto acusado de abuso sexual contra menor se vaya del sector"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/127411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=127411"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/127411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/127413"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=127411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=127411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=127411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}