{"id":127418,"date":"2024-01-15T22:35:41","date_gmt":"2024-01-16T01:35:41","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=127418"},"modified":"2024-01-15T22:33:25","modified_gmt":"2024-01-16T01:33:25","slug":"a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/","title":{"rendered":"\u00a1A prepararse!: Aconcagua vivir\u00e1 intensa ola de calor durante la presente semana"},"content":{"rendered":"<ul>\n<li><strong>Para el viernes y el fin de semana, se espera que los term\u00f3metros superen incluso los 42 grados.-<\/strong><\/li>\n<\/ul>\n<p>A prepararse para el calor intenso que tendremos durante esta semana en nuestro valle del Aconcagua, con temperaturas que podr\u00edan alcanzar f\u00e1cilmente los 35 a 38 grados; y eso no es todo, porque para el viernes y el fin de semana, se espera que los term\u00f3metros alcancen los generosos y no despreciables 42 grados y m\u00e1s.<\/p>\n<p><strong>Manuel Vicencio<\/strong>, de <strong>@aconcaguaclima<\/strong>, coment\u00f3 que <em>\u00abvamos a tener durante esta semana temperaturas de 35 grados hacia arriba, hasta 38, esto puede variar en el sentido de si en la costa se produce ingreso de neblina y que esta entre un poco al valle, es lo que nos puede salvar de estos registros\u00bb. <\/em><\/p>\n<p>Y para el fin de semana la cosa se viene peor con las altas temperaturas, <em>\u00abya se habla de esta ola de calor que vamos a vivir durante esta semana, con un peak el pr\u00f3ximo viernes, con temperaturas donde podr\u00edamos superar los 41 \u00f3 42 grados\u00bb,<\/em> agreg\u00f3 Vicencio.<\/p>\n<p>Intenso poder del astro rey que vamos a sentir en nuestro valle y que por consiguiente elevar\u00e1 la radiaci\u00f3n ultravioleta, por ende, el llamado es a evitar exponerse a las horas de mayor temperatura por el riesgo a la salud que esto provoca.<\/p>\n<p>\u00ab<em>La radiaci\u00f3n solar sigue en nivel 12, muy extremo, el cuidado de la piel y los ojos es importante\u00bb,<\/em> coment\u00f3 Vicencio, quien adem\u00e1s recomend\u00f3 que hay que <em>\u00abpreocuparnos del calor, bloqueador, hidratados porque el calor ser\u00e1 intenso y sobre todo para el fin de semana\u00bb.<\/em><\/p>\n<figure id=\"attachment_127419\" aria-describedby=\"caption-attachment-127419\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-127419\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/calor-1.jpg\" alt=\"Intensa ola de calor se registrar\u00e1 durante esta semana en Aconcagua. \" width=\"699\" height=\"459\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/calor-1.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/calor-1-300x197.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/calor-1-150x98.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/calor-1-696x457.jpg 696w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/calor-1-640x420.jpg 640w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-127419\" class=\"wp-caption-text\">Intensa ola de calor se registrar\u00e1 durante esta semana en Aconcagua.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Para el viernes y el fin de semana, se espera que los term\u00f3metros superen incluso los 42 grados.- A prepararse para el calor intenso que tendremos durante esta semana en nuestro valle del Aconcagua, con temperaturas que podr\u00edan alcanzar f\u00e1cilmente los 35 a 38 grados; y eso no es todo, porque para el viernes y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":127419,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-127418","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cronica-2"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1A prepararse!: Aconcagua vivir\u00e1 intensa ola de calor durante la presente semana - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1A prepararse!: Aconcagua vivir\u00e1 intensa ola de calor durante la presente semana - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Para el viernes y el fin de semana, se espera que los term\u00f3metros superen incluso los 42 grados.- A prepararse para el calor intenso que tendremos durante esta semana en nuestro valle del Aconcagua, con temperaturas que podr\u00edan alcanzar f\u00e1cilmente los 35 a 38 grados; y eso no es todo, porque para el viernes y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-16T01:35:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/calor-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"699\" \/>\n\t<meta property=\"og:image:height\" content=\"459\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"\u00a1A prepararse!: Aconcagua vivir\u00e1 intensa ola de calor durante la presente semana\",\"datePublished\":\"2024-01-16T01:35:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\\\/\"},\"wordCount\":294,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/calor-1.jpg\",\"articleSection\":[\"Cr\u00f3nica\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\\\/\",\"name\":\"\u00a1A prepararse!: Aconcagua vivir\u00e1 intensa ola de calor durante la presente semana - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/calor-1.jpg\",\"datePublished\":\"2024-01-16T01:35:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/calor-1.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/calor-1.jpg\",\"width\":699,\"height\":459,\"caption\":\"Intensa ola de calor se registrar\u00e1 durante esta semana en Aconcagua.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1A prepararse!: Aconcagua vivir\u00e1 intensa ola de calor durante la presente semana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1A prepararse!: Aconcagua vivir\u00e1 intensa ola de calor durante la presente semana - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1A prepararse!: Aconcagua vivir\u00e1 intensa ola de calor durante la presente semana - Diario El Trabajo","og_description":"Para el viernes y el fin de semana, se espera que los term\u00f3metros superen incluso los 42 grados.- A prepararse para el calor intenso que tendremos durante esta semana en nuestro valle del Aconcagua, con temperaturas que podr\u00edan alcanzar f\u00e1cilmente los 35 a 38 grados; y eso no es todo, porque para el viernes y [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2024-01-16T01:35:41+00:00","og_image":[{"width":699,"height":459,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/calor-1.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"\u00a1A prepararse!: Aconcagua vivir\u00e1 intensa ola de calor durante la presente semana","datePublished":"2024-01-16T01:35:41+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/"},"wordCount":294,"commentCount":0,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/calor-1.jpg","articleSection":["Cr\u00f3nica"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/","url":"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/","name":"\u00a1A prepararse!: Aconcagua vivir\u00e1 intensa ola de calor durante la presente semana - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/calor-1.jpg","datePublished":"2024-01-16T01:35:41+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/calor-1.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/01\/calor-1.jpg","width":699,"height":459,"caption":"Intensa ola de calor se registrar\u00e1 durante esta semana en Aconcagua."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/a-prepararse-aconcagua-vivira-intensa-ola-de-calor-durante-la-presente-semana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"\u00a1A prepararse!: Aconcagua vivir\u00e1 intensa ola de calor durante la presente semana"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/127418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=127418"}],"version-history":[{"count":0,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/127418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/127419"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=127418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=127418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=127418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}