{"id":133418,"date":"2024-11-21T21:50:25","date_gmt":"2024-11-22T00:50:25","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=133418"},"modified":"2024-11-21T21:43:23","modified_gmt":"2024-11-22T00:43:23","slug":"el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/","title":{"rendered":"El Arte y el Patrimonio Infantil: una jornada de magia en el Buen Pastor"},"content":{"rendered":"<p>En el marco del D\u00eda del Patrimonio de Ni\u00f1os, Ni\u00f1as y J\u00f3venes, la Fundaci\u00f3n Buen Pastor, con la colaboraci\u00f3n del Departamento de Cultura y la Municipalidad de San Felipe, fue escenario de una actividad \u00fanica que puso en el centro la conexi\u00f3n entre el arte, la infancia y el patrimonio.<\/p>\n<p>La actividad principal estuvo a cargo de <strong>Ninatitiricuenta<\/strong>, un proyecto que utiliza los t\u00edteres y los cuentos interactivos como herramientas para fomentar la imaginaci\u00f3n, la participaci\u00f3n activa y la conexi\u00f3n comunitaria. Con el apoyo del artista local <strong>Maicol Cruces<\/strong>, este espect\u00e1culo encant\u00f3 a ni\u00f1os y familias, ofreciendo una experiencia \u00fanica que combina narraci\u00f3n teatral, efectos visuales y din\u00e1micas l\u00fadicas dise\u00f1adas para estimular a los participantes en un mundo cada vez m\u00e1s digitalizado.<\/p>\n<p>Ninatitiricuenta tiene un objetivo claro: llevar arte y cultura a todos los territorios, demostrando que el arte no es un privilegio, sino una necesidad. En el contexto del D\u00eda del Patrimonio, esta propuesta busc\u00f3 destacar la importancia de rescatar nuestras ra\u00edces culturales mientras se crean espacios de participaci\u00f3n y aprendizaje para las nuevas generaciones.<\/p>\n<p>\u00ab<em>La idea es que los ni\u00f1os no solo sean espectadores, sino protagonistas. Queremos que descubran, se emocionen y se conecten con el entorno, porque el arte tiene el poder de transformar realidades\u00bb,<\/em> se\u00f1ala <strong>Nina Legrand<\/strong>, directora de Ninatitiricuenta.<\/p>\n<p>Gracias al liderazgo de la Fundaci\u00f3n Buen Pastor y la colaboraci\u00f3n del Departamento de Cultura y la Municipalidad de San Felipe, esta jornada demostr\u00f3 que la cultura puede ser accesible para todos, consolid\u00e1ndose como un puente entre el arte y la comunidad.<\/p>\n<p>Ninatitiricuenta reafirma su compromiso de seguir llevando espect\u00e1culos que inspiren, ense\u00f1en y conecten a las familias, mostrando que el arte es una herramienta esencial para preservar el patrimonio y construir comunidades llenas de esperanza y creatividad.<\/p>\n<p>\u00ab<em>\u00a1Sigamos llevando la magia del arte a todos los rincones!\u00bb,<\/em> concluy\u00f3 Nina Legrand.<\/p>\n<figure id=\"attachment_133419\" aria-describedby=\"caption-attachment-133419\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-133419\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/11\/nina-1.jpg\" alt=\"La actividad principal estuvo a cargo de Ninatitiricuenta, un proyecto que utiliza los t\u00edteres y los cuentos interactivos como herramientas para fomentar la imaginaci\u00f3n, la participaci\u00f3n activa y la conexi\u00f3n comunitaria, a cargo de Nina Legrand y el apoyo del artista local Maicol Cruces.\" width=\"700\" height=\"450\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/11\/nina-1.jpg 700w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/11\/nina-1-300x193.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/11\/nina-1-653x420.jpg 653w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/11\/nina-1-150x96.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/11\/nina-1-696x447.jpg 696w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-133419\" class=\"wp-caption-text\">La actividad principal estuvo a cargo de Ninatitiricuenta, un proyecto que utiliza los t\u00edteres y los cuentos interactivos como herramientas para fomentar la imaginaci\u00f3n, la participaci\u00f3n activa y la conexi\u00f3n comunitaria, a cargo de Nina Legrand y el apoyo del artista local Maicol Cruces.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del D\u00eda del Patrimonio de Ni\u00f1os, Ni\u00f1as y J\u00f3venes, la Fundaci\u00f3n Buen Pastor, con la colaboraci\u00f3n del Departamento de Cultura y la Municipalidad de San Felipe, fue escenario de una actividad \u00fanica que puso en el centro la conexi\u00f3n entre el arte, la infancia y el patrimonio. La actividad principal estuvo a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":133419,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":{"0":"post-133418","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arte-y-cultura"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Arte y el Patrimonio Infantil: una jornada de magia en el Buen Pastor - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Arte y el Patrimonio Infantil: una jornada de magia en el Buen Pastor - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"En el marco del D\u00eda del Patrimonio de Ni\u00f1os, Ni\u00f1as y J\u00f3venes, la Fundaci\u00f3n Buen Pastor, con la colaboraci\u00f3n del Departamento de Cultura y la Municipalidad de San Felipe, fue escenario de una actividad \u00fanica que puso en el centro la conexi\u00f3n entre el arte, la infancia y el patrimonio. La actividad principal estuvo a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-22T00:50:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/11\/nina-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"El Arte y el Patrimonio Infantil: una jornada de magia en el Buen Pastor\",\"datePublished\":\"2024-11-22T00:50:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\\\/\"},\"wordCount\":402,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/nina-1.jpg\",\"articleSection\":[\"Arte y Cultura\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\\\/\",\"name\":\"El Arte y el Patrimonio Infantil: una jornada de magia en el Buen Pastor - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/nina-1.jpg\",\"datePublished\":\"2024-11-22T00:50:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/nina-1.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/nina-1.jpg\",\"width\":700,\"height\":450,\"caption\":\"La actividad principal estuvo a cargo de Ninatitiricuenta, un proyecto que utiliza los t\u00edteres y los cuentos interactivos como herramientas para fomentar la imaginaci\u00f3n, la participaci\u00f3n activa y la conexi\u00f3n comunitaria, a cargo de Nina Legrand y el apoyo del artista local Maicol Cruces.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Arte y el Patrimonio Infantil: una jornada de magia en el Buen Pastor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Arte y el Patrimonio Infantil: una jornada de magia en el Buen Pastor - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/","og_locale":"es_ES","og_type":"article","og_title":"El Arte y el Patrimonio Infantil: una jornada de magia en el Buen Pastor - Diario El Trabajo","og_description":"En el marco del D\u00eda del Patrimonio de Ni\u00f1os, Ni\u00f1as y J\u00f3venes, la Fundaci\u00f3n Buen Pastor, con la colaboraci\u00f3n del Departamento de Cultura y la Municipalidad de San Felipe, fue escenario de una actividad \u00fanica que puso en el centro la conexi\u00f3n entre el arte, la infancia y el patrimonio. La actividad principal estuvo a [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2024-11-22T00:50:25+00:00","og_image":[{"width":700,"height":450,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/11\/nina-1.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"El Arte y el Patrimonio Infantil: una jornada de magia en el Buen Pastor","datePublished":"2024-11-22T00:50:25+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/"},"wordCount":402,"commentCount":0,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/11\/nina-1.jpg","articleSection":["Arte y Cultura"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/","url":"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/","name":"El Arte y el Patrimonio Infantil: una jornada de magia en el Buen Pastor - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/11\/nina-1.jpg","datePublished":"2024-11-22T00:50:25+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/11\/nina-1.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/11\/nina-1.jpg","width":700,"height":450,"caption":"La actividad principal estuvo a cargo de Ninatitiricuenta, un proyecto que utiliza los t\u00edteres y los cuentos interactivos como herramientas para fomentar la imaginaci\u00f3n, la participaci\u00f3n activa y la conexi\u00f3n comunitaria, a cargo de Nina Legrand y el apoyo del artista local Maicol Cruces."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/el-arte-y-el-patrimonio-infantil-una-jornada-de-magia-en-el-buen-pastor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"El Arte y el Patrimonio Infantil: una jornada de magia en el Buen Pastor"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/133418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=133418"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/133418\/revisions"}],"predecessor-version":[{"id":133420,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/133418\/revisions\/133420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/133419"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=133418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=133418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=133418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}