{"id":134594,"date":"2025-01-21T20:50:40","date_gmt":"2025-01-21T23:50:40","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=134594"},"modified":"2025-01-21T20:50:40","modified_gmt":"2025-01-21T23:50:40","slug":"universidad-de-aconcagua-35-anos-formando-profesionales","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/","title":{"rendered":"Universidad de Aconcagua: 35 a\u00f1os formando profesionales"},"content":{"rendered":"<ul>\n<li><strong>Casa de estudios nacida en San Felipe celebr\u00f3 recientemente un nuevo aniversario institucional.-<\/strong><\/li>\n<\/ul>\n<p>En respuesta a la demanda de la comunidad y autoridades locales, en diciembre de 1989 se fund\u00f3 en San Felipe, la Universidad de Aconcagua (UAC), con el prop\u00f3sito de\u00a0\u00a0 brindar oportunidades de desarrollo profesional a j\u00f3venes y trabajadores del Valle de Aconcagua, del cual tom\u00f3 su nombre.<\/p>\n<p>Con ese esp\u00edritu, y con el af\u00e1n de contribuir al desarrollo nacional, con una mirada regional, a trav\u00e9s de los a\u00f1os la UAC extendi\u00f3 su gesti\u00f3n a otras regiones del pa\u00eds, encontr\u00e1ndose actualmente, tras 35 a\u00f1os de vida institucional, presente desde Calama a Ancud, cumpliendo con el mandato de su\u00a0 Misi\u00f3n y Visi\u00f3n, cuya mejor evidencia, son sus m\u00e1s de 20.000 titulados\/as, que la han convertido en un aut\u00e9ntico factor de movilidad social, toda vez que, sobre el 70%\u00a0 de ellos corresponde a primera generaci\u00f3n en acceder y culminar estudios universitarios.<\/p>\n<p>Actualmente, la Universidad de Aconcagua ha iniciado un nuevo Proceso de Autoevaluaci\u00f3n, orientado a la Acreditaci\u00f3n Institucional, en el marco de la supervisi\u00f3n del Consejo Nacional de Educaci\u00f3n (CNED), en curso. En dicho contexto, junto a la docencia de pregrado, la UAC avanza sostenidamente en otras dimensiones propias del quehacer de toda casa de estudios superiores, como la investigaci\u00f3n y la vinculaci\u00f3n con el medio, con\u00a0 pol\u00edticas y mecanismos de aseguramiento de la calidad claramente definidos, con el fortaleciendo de sus equipos, y la participaci\u00f3n en redes colaborativas nacionales e internacionales, sin perder de vista la esencia regionalista de su concepci\u00f3n, la que se plasma en cada una de sus sedes, constituyendo un sello distintivo.<\/p>\n<p>\u00ab<em>Estar al frente de sede San Felipe de la UAC es un honor y una gran responsabilidad. Se trata de la sede fundacional, donde todo parti\u00f3 y desde donde nos proyectamos al futuro, siempre comprometidos con nuestro querido Valle del Aconcagua y su gente\u00bb<\/em>, se\u00f1al\u00f3 <strong>Edith Fuentes Ortega<\/strong>, directora de la sede San Felipe.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>ADMISI\u00d3N 2025 EN CURSO<\/strong><\/p>\n<p>La directora Fuentes inform\u00f3 tambi\u00e9n, que est\u00e1 en pleno desarrollo el Proceso de Admisi\u00f3n 2025, para el que se ha dispuesto de un total de 300 vacantes en Sede San Felipe, distribuidas en sus carreras profesionales de Derecho, Psicolog\u00eda, Enfermer\u00eda, Kinesiolog\u00eda, Terapia Ocupacional; las carreras t\u00e9cnicas de nivel superior en Agronom\u00eda y Enfermer\u00eda; adem\u00e1s del Programa de Continuidad de Estudios de Agronom\u00eda, dirigido a t\u00e9cnicos del \u00e1rea.<\/p>\n<p><em>\u00abA la fecha ya se han completado m\u00e1s de un tercio de las vacantes disponibles, lo que da cuenta de la confianza e identificaci\u00f3n de la gente de San Felipe con su universidad\u00bb<\/em>, se\u00f1al\u00f3 Fuentes, precisando que si bien el proceso se extiende hasta abril, aquello est\u00e1 condicionado a que se cuente con cupos disponibles, por lo que formul\u00f3 un llamado a los interesados a matricularse a la brevedad, para lo que deben acercarse a la sede,\u00a0 ubicada en Av. Miraflores 2260.<\/p>\n<figure id=\"attachment_134596\" aria-describedby=\"caption-attachment-134596\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-134596\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-1.jpg\" alt=\"Edith Fuentes Ortega, directora de la sede San Felipe de la Universidad de Aconcagua.\" width=\"699\" height=\"484\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-1.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-1-300x208.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-1-607x420.jpg 607w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-1-150x104.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-1-218x150.jpg 218w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-1-696x482.jpg 696w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-1-100x70.jpg 100w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-134596\" class=\"wp-caption-text\">Edith Fuentes Ortega, directora de la sede San Felipe de la Universidad de Aconcagua.<\/figcaption><\/figure>\n<figure id=\"attachment_134595\" aria-describedby=\"caption-attachment-134595\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-134595\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-2.jpg\" alt=\"La UAC recientemente celebr\u00f3 35 a\u00f1os formando profesionales.\" width=\"700\" height=\"525\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-2.jpg 700w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-2-300x225.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-2-560x420.jpg 560w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-2-80x60.jpg 80w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-2-150x113.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-2-696x522.jpg 696w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-2-265x198.jpg 265w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-134595\" class=\"wp-caption-text\">La UAC recientemente celebr\u00f3 35 a\u00f1os formando profesionales.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Casa de estudios nacida en San Felipe celebr\u00f3 recientemente un nuevo aniversario institucional.- En respuesta a la demanda de la comunidad y autoridades locales, en diciembre de 1989 se fund\u00f3 en San Felipe, la Universidad de Aconcagua (UAC), con el prop\u00f3sito de\u00a0\u00a0 brindar oportunidades de desarrollo profesional a j\u00f3venes y trabajadores del Valle de Aconcagua, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":134595,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-134594","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cronica-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Universidad de Aconcagua: 35 a\u00f1os formando profesionales - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Universidad de Aconcagua: 35 a\u00f1os formando profesionales - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Casa de estudios nacida en San Felipe celebr\u00f3 recientemente un nuevo aniversario institucional.- En respuesta a la demanda de la comunidad y autoridades locales, en diciembre de 1989 se fund\u00f3 en San Felipe, la Universidad de Aconcagua (UAC), con el prop\u00f3sito de\u00a0\u00a0 brindar oportunidades de desarrollo profesional a j\u00f3venes y trabajadores del Valle de Aconcagua, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T23:50:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/universidad-de-aconcagua-35-anos-formando-profesionales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/universidad-de-aconcagua-35-anos-formando-profesionales\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Universidad de Aconcagua: 35 a\u00f1os formando profesionales\",\"datePublished\":\"2025-01-21T23:50:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/universidad-de-aconcagua-35-anos-formando-profesionales\\\/\"},\"wordCount\":551,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/universidad-de-aconcagua-35-anos-formando-profesionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/UNIVERSIDAD-ACONCAGUA-2.jpg\",\"articleSection\":[\"Cr\u00f3nica\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/universidad-de-aconcagua-35-anos-formando-profesionales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/universidad-de-aconcagua-35-anos-formando-profesionales\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/universidad-de-aconcagua-35-anos-formando-profesionales\\\/\",\"name\":\"Universidad de Aconcagua: 35 a\u00f1os formando profesionales - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/universidad-de-aconcagua-35-anos-formando-profesionales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/universidad-de-aconcagua-35-anos-formando-profesionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/UNIVERSIDAD-ACONCAGUA-2.jpg\",\"datePublished\":\"2025-01-21T23:50:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/universidad-de-aconcagua-35-anos-formando-profesionales\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/universidad-de-aconcagua-35-anos-formando-profesionales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/universidad-de-aconcagua-35-anos-formando-profesionales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/UNIVERSIDAD-ACONCAGUA-2.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/UNIVERSIDAD-ACONCAGUA-2.jpg\",\"width\":700,\"height\":525,\"caption\":\"La UAC recientemente celebr\u00f3 35 a\u00f1os formando profesionales.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/universidad-de-aconcagua-35-anos-formando-profesionales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Universidad de Aconcagua: 35 a\u00f1os formando profesionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Universidad de Aconcagua: 35 a\u00f1os formando profesionales - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/","og_locale":"es_ES","og_type":"article","og_title":"Universidad de Aconcagua: 35 a\u00f1os formando profesionales - Diario El Trabajo","og_description":"Casa de estudios nacida en San Felipe celebr\u00f3 recientemente un nuevo aniversario institucional.- En respuesta a la demanda de la comunidad y autoridades locales, en diciembre de 1989 se fund\u00f3 en San Felipe, la Universidad de Aconcagua (UAC), con el prop\u00f3sito de\u00a0\u00a0 brindar oportunidades de desarrollo profesional a j\u00f3venes y trabajadores del Valle de Aconcagua, [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2025-01-21T23:50:40+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-2.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Universidad de Aconcagua: 35 a\u00f1os formando profesionales","datePublished":"2025-01-21T23:50:40+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/"},"wordCount":551,"commentCount":0,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-2.jpg","articleSection":["Cr\u00f3nica"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/","url":"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/","name":"Universidad de Aconcagua: 35 a\u00f1os formando profesionales - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-2.jpg","datePublished":"2025-01-21T23:50:40+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-2.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/01\/UNIVERSIDAD-ACONCAGUA-2.jpg","width":700,"height":525,"caption":"La UAC recientemente celebr\u00f3 35 a\u00f1os formando profesionales."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/universidad-de-aconcagua-35-anos-formando-profesionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Universidad de Aconcagua: 35 a\u00f1os formando profesionales"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/134594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=134594"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/134594\/revisions"}],"predecessor-version":[{"id":134597,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/134594\/revisions\/134597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/134595"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=134594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=134594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=134594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}