{"id":137692,"date":"2025-05-29T22:11:37","date_gmt":"2025-05-30T01:11:37","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=137692"},"modified":"2025-05-29T22:11:37","modified_gmt":"2025-05-30T01:11:37","slug":"allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/","title":{"rendered":"Allanamiento en la c\u00e1rcel permite incautar m\u00e1s de 200 dosis de droga"},"content":{"rendered":"<ul>\n<li><strong>Adem\u00e1s se requis\u00f3 licor artesanal, armas blancas y tel\u00e9fonos celulares.-<\/strong><\/li>\n<\/ul>\n<p>Dependencias habitadas por m\u00e1s de 150 personas privadas de libertad fueron revisadas exhaustivamente por personal de Gendarmer\u00eda. Esto, durante un procedimiento de registro y allanamiento realizado este mi\u00e9rcoles en el Centro de Cumplimiento Penitenciario (CCP) de San Felipe.<\/p>\n<p>El operativo, que ten\u00eda por finalidad reforzar la seguridad de la unidad penal y mantener el control de la misma, comenz\u00f3 a las 18:40 horas y cont\u00f3 con la participaci\u00f3n de funcionarios de la Unidad de Servicios Especiales Penitenciarios de Los Andes y Quillota, adem\u00e1s de personal del mismo CCP.<\/p>\n<p>El jefe (s) del establecimiento sanfelipe\u00f1o, teniente coronel <strong>Carlos Ortiz S\u00e1nchez<\/strong>, entreg\u00f3 detalles del procedimiento.<\/p>\n<p>\u00ab<em>Se realiz\u00f3 un registro de allanamiento extraordinario en la unidad, el cual fue exitoso, logrando incautar m\u00e1s de 200 dosis de drogas de distintos tipos, adem\u00e1s de armas blancas hechizas y licor artesanal. Sacar esta gran cantidad de droga de circulaci\u00f3n desde dentro de las c\u00e1rceles nos ayuda bastante a la tranquilidad y al manejo de la poblaci\u00f3n penal por parte del personal\u00bb<\/em>.<\/p>\n<p>Por su parte, el jefe operativo regional, teniente coronel <strong>Renzo S\u00e1nchez Recabal<\/strong>, destac\u00f3 la relevancia que tiene la constante ejecuci\u00f3n de estos operativos.<\/p>\n<p>\u00ab<em>Dentro de la seguridad penitenciaria, hemos desarrollado este tipo de procedimiento extraordinario y, obviamente, guarda relaci\u00f3n con salvaguardar la integridad de los internos y del personal de Gendarmer\u00eda. Por esto se realizan este tipo de procedimientos extraordinarios fuera del horario laboral, para incautar el m\u00e1ximo de elementos prohibidos dentro de la unidad penal\u00bb<\/em>, indic\u00f3.<\/p>\n<p>De la droga incautada se inform\u00f3 al Ministerio P\u00fablico, quien determin\u00f3 el procedimiento a seguir.<\/p>\n<figure id=\"attachment_137693\" aria-describedby=\"caption-attachment-137693\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-137693\" src=\"http:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-2.jpg\" alt=\"Allanamiento se realiz\u00f3 este mi\u00e9rcoles en el CCP San Felipe.\" width=\"699\" height=\"435\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-2.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-2-300x187.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-2-675x420.jpg 675w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-2-150x93.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-2-696x433.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-137693\" class=\"wp-caption-text\">Allanamiento se realiz\u00f3 este mi\u00e9rcoles en el CCP San Felipe.<\/figcaption><\/figure>\n<figure id=\"attachment_137694\" aria-describedby=\"caption-attachment-137694\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-137694\" src=\"http:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-1.jpg\" alt=\"Incautan m\u00e1s de 200 dosis de droga.\" width=\"699\" height=\"502\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-1.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-1-300x215.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-1-585x420.jpg 585w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-1-150x108.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-1-696x500.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-137694\" class=\"wp-caption-text\">Incautan m\u00e1s de 200 dosis de droga.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s se requis\u00f3 licor artesanal, armas blancas y tel\u00e9fonos celulares.- Dependencias habitadas por m\u00e1s de 150 personas privadas de libertad fueron revisadas exhaustivamente por personal de Gendarmer\u00eda. Esto, durante un procedimiento de registro y allanamiento realizado este mi\u00e9rcoles en el Centro de Cumplimiento Penitenciario (CCP) de San Felipe. El operativo, que ten\u00eda por finalidad reforzar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":137694,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-137692","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Allanamiento en la c\u00e1rcel permite incautar m\u00e1s de 200 dosis de droga - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Allanamiento en la c\u00e1rcel permite incautar m\u00e1s de 200 dosis de droga - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Adem\u00e1s se requis\u00f3 licor artesanal, armas blancas y tel\u00e9fonos celulares.- Dependencias habitadas por m\u00e1s de 150 personas privadas de libertad fueron revisadas exhaustivamente por personal de Gendarmer\u00eda. Esto, durante un procedimiento de registro y allanamiento realizado este mi\u00e9rcoles en el Centro de Cumplimiento Penitenciario (CCP) de San Felipe. El operativo, que ten\u00eda por finalidad reforzar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-30T01:11:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"699\" \/>\n\t<meta property=\"og:image:height\" content=\"502\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Allanamiento en la c\u00e1rcel permite incautar m\u00e1s de 200 dosis de droga\",\"datePublished\":\"2025-05-30T01:11:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\\\/\"},\"wordCount\":332,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/DROGA-1.jpg\",\"articleSection\":[\"Policial\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\\\/\",\"name\":\"Allanamiento en la c\u00e1rcel permite incautar m\u00e1s de 200 dosis de droga - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/DROGA-1.jpg\",\"datePublished\":\"2025-05-30T01:11:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/DROGA-1.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/DROGA-1.jpg\",\"width\":699,\"height\":502,\"caption\":\"Incautan m\u00e1s de 200 dosis de droga.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allanamiento en la c\u00e1rcel permite incautar m\u00e1s de 200 dosis de droga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Allanamiento en la c\u00e1rcel permite incautar m\u00e1s de 200 dosis de droga - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/","og_locale":"es_ES","og_type":"article","og_title":"Allanamiento en la c\u00e1rcel permite incautar m\u00e1s de 200 dosis de droga - Diario El Trabajo","og_description":"Adem\u00e1s se requis\u00f3 licor artesanal, armas blancas y tel\u00e9fonos celulares.- Dependencias habitadas por m\u00e1s de 150 personas privadas de libertad fueron revisadas exhaustivamente por personal de Gendarmer\u00eda. Esto, durante un procedimiento de registro y allanamiento realizado este mi\u00e9rcoles en el Centro de Cumplimiento Penitenciario (CCP) de San Felipe. El operativo, que ten\u00eda por finalidad reforzar [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2025-05-30T01:11:37+00:00","og_image":[{"width":699,"height":502,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-1.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Allanamiento en la c\u00e1rcel permite incautar m\u00e1s de 200 dosis de droga","datePublished":"2025-05-30T01:11:37+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/"},"wordCount":332,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-1.jpg","articleSection":["Policial"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/","url":"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/","name":"Allanamiento en la c\u00e1rcel permite incautar m\u00e1s de 200 dosis de droga - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-1.jpg","datePublished":"2025-05-30T01:11:37+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-1.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/05\/DROGA-1.jpg","width":699,"height":502,"caption":"Incautan m\u00e1s de 200 dosis de droga."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/allanamiento-en-la-carcel-permite-incautar-mas-de-200-dosis-de-droga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Allanamiento en la c\u00e1rcel permite incautar m\u00e1s de 200 dosis de droga"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/137692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=137692"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/137692\/revisions"}],"predecessor-version":[{"id":137695,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/137692\/revisions\/137695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/137694"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=137692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=137692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=137692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}