{"id":137731,"date":"2025-06-01T21:21:04","date_gmt":"2025-06-02T00:21:04","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=137731"},"modified":"2025-06-01T21:21:04","modified_gmt":"2025-06-02T00:21:04","slug":"halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/","title":{"rendered":"Halcones es sorprendido y sufre una severa derrota en su propia casa"},"content":{"rendered":"<p>En su retorno a la competencia C de la Arusa, Los Halcones de Aconcagua sufrieron un inesperado y, al mismo tiempo, expresivo traspi\u00e9 frente al Old Newlanders, cuadro ante el cual terminaron inclin\u00e1ndose 25 a 66 en el duelo disputado durante la jornada del s\u00e1bado \u00faltimo en el Estadio Municipal de Calle Larga.<\/p>\n<p>Este traspi\u00e9 trajo consecuencias para los aconcag\u00fcinos, al quedar relegados en la quinta posici\u00f3n de la tabla, dejando de paso importantes lecciones para m\u00e1s adelante, donde no podr\u00e1n volver a cometer errores como recibir tres tarjetas rojas y salirse del sistema y estrategia de juego, cosa que ante rivales livianos y muy r\u00e1pidos como lo fue el \u00faltimo, terminan pag\u00e1ndose muy caro. <em>\u00abLa cancha se nos hizo enorme y fue imposible cubrirla\u00bb<\/em>, relat\u00f3 a nuestro medio un jugador andino.<\/p>\n<p>Resultados:<\/p>\n<p>Lions RC 75 \u2013 UST 14; Gauchos RC 45 \u2013 Universidad de Chile 13; Halcones 25 \u2013 Old Newlanders 66.<\/p>\n<p>Al cierre de la presente edici\u00f3n de <strong>El Trabajo Deportivo<\/strong> jugaban San Bartolom\u00e9 contra Trapiales.<\/p>\n<p>Tabla de Posiciones<\/p>\n<p>Lugar\u00a0 Ptos.<\/p>\n<p>Gauchos RC 18<\/p>\n<p>Lions RC 14<\/p>\n<p>Old Newlanders 13<\/p>\n<p>Mano Rugby 12<\/p>\n<p>Halcones RC 12<\/p>\n<p>U. de Chile 9<\/p>\n<p>Trapiales 8<\/p>\n<p>San Bartolom\u00e9 6<\/p>\n<p>UST 1<\/p>\n<figure id=\"attachment_137732\" aria-describedby=\"caption-attachment-137732\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-137732\" src=\"http:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Halcones.jpg\" alt=\"Despu\u00e9s de dos semanas de inactividad, los Halcones volvieron a competir en Arusa. \" width=\"699\" height=\"494\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Halcones.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Halcones-300x212.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Halcones-594x420.jpg 594w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Halcones-150x106.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Halcones-696x492.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-137732\" class=\"wp-caption-text\">Despu\u00e9s de dos semanas de inactividad, los Halcones volvieron a competir en Arusa.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En su retorno a la competencia C de la Arusa, Los Halcones de Aconcagua sufrieron un inesperado y, al mismo tiempo, expresivo traspi\u00e9 frente al Old Newlanders, cuadro ante el cual terminaron inclin\u00e1ndose 25 a 66 en el duelo disputado durante la jornada del s\u00e1bado \u00faltimo en el Estadio Municipal de Calle Larga. Este traspi\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":137732,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-137731","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Halcones es sorprendido y sufre una severa derrota en su propia casa - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Halcones es sorprendido y sufre una severa derrota en su propia casa - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"En su retorno a la competencia C de la Arusa, Los Halcones de Aconcagua sufrieron un inesperado y, al mismo tiempo, expresivo traspi\u00e9 frente al Old Newlanders, cuadro ante el cual terminaron inclin\u00e1ndose 25 a 66 en el duelo disputado durante la jornada del s\u00e1bado \u00faltimo en el Estadio Municipal de Calle Larga. Este traspi\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-02T00:21:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Halcones.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"699\" \/>\n\t<meta property=\"og:image:height\" content=\"494\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Halcones es sorprendido y sufre una severa derrota en su propia casa\",\"datePublished\":\"2025-06-02T00:21:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\\\/\"},\"wordCount\":221,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Halcones.jpg\",\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\\\/\",\"name\":\"Halcones es sorprendido y sufre una severa derrota en su propia casa - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Halcones.jpg\",\"datePublished\":\"2025-06-02T00:21:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Halcones.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Halcones.jpg\",\"width\":699,\"height\":494,\"caption\":\"Despu\u00e9s de dos semanas de inactividad, los Halcones volvieron a competir en Arusa.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Halcones es sorprendido y sufre una severa derrota en su propia casa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Halcones es sorprendido y sufre una severa derrota en su propia casa - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/","og_locale":"es_ES","og_type":"article","og_title":"Halcones es sorprendido y sufre una severa derrota en su propia casa - Diario El Trabajo","og_description":"En su retorno a la competencia C de la Arusa, Los Halcones de Aconcagua sufrieron un inesperado y, al mismo tiempo, expresivo traspi\u00e9 frente al Old Newlanders, cuadro ante el cual terminaron inclin\u00e1ndose 25 a 66 en el duelo disputado durante la jornada del s\u00e1bado \u00faltimo en el Estadio Municipal de Calle Larga. Este traspi\u00e9 [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2025-06-02T00:21:04+00:00","og_image":[{"width":699,"height":494,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Halcones.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Halcones es sorprendido y sufre una severa derrota en su propia casa","datePublished":"2025-06-02T00:21:04+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/"},"wordCount":221,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Halcones.jpg","articleSection":["Deportes"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/","url":"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/","name":"Halcones es sorprendido y sufre una severa derrota en su propia casa - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Halcones.jpg","datePublished":"2025-06-02T00:21:04+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Halcones.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Halcones.jpg","width":699,"height":494,"caption":"Despu\u00e9s de dos semanas de inactividad, los Halcones volvieron a competir en Arusa."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/halcones-es-sorprendido-y-sufre-una-severa-derrota-en-su-propia-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Halcones es sorprendido y sufre una severa derrota en su propia casa"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/137731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=137731"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/137731\/revisions"}],"predecessor-version":[{"id":137733,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/137731\/revisions\/137733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/137732"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=137731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=137731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=137731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}