{"id":137796,"date":"2025-06-03T21:35:08","date_gmt":"2025-06-04T00:35:08","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=137796"},"modified":"2025-06-03T21:35:08","modified_gmt":"2025-06-04T00:35:08","slug":"cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/","title":{"rendered":"Cuatro equipos de la zona avanzaron al cuadro\u00a0de los dieciseisavos de final de la \u2018Orejona\u2019 femenina"},"content":{"rendered":"<p>Durante el fin de semana pasado se jugaron los partidos de revancha para confirmar el cuadro de los treinta y dos mejores equipos femeninos que compiten en la versi\u00f3n 2025 de la \u2018Copa de Campeones Femenina\u2019.<\/p>\n<p>Dentro de ese selecto grupo de conjuntos femeninos, sobresalen cuatro oncenas de nuestra zona, equipos que ahora y desde este fin de semana jugar\u00e1n los partidos de ida con el tremendo objetivo de sortear esta etapa y meterse a la ronda de los octavos de final del torneo de balompi\u00e9 amateur femenino m\u00e1s importante de la Quinta Regi\u00f3n.<\/p>\n<p>Los equipos de nuestra zona que disputar\u00e1n esta etapa de la \u2018Orejona\u2019 de mujeres son: La Higuera y Las Cadenas de Santa Mar\u00eda; Pe\u00f1arol Reinoso de Catemu; Libertad de Putaendo. En el cuadro por la parte de arriba va La Higuera, mientras que los otros tres van por abajo.<\/p>\n<p>Las llaves para las aconcag\u00fcinas son:<\/p>\n<p>La Higuera &#8211; Las Ventanas (Asociaci\u00f3n Las Ventanas).<\/p>\n<p>Libertad &#8211; C\u00f3ndor (La Ligua).<\/p>\n<p>Pe\u00f1arol Reinoso &#8211; Glorias Navales (Vi\u00f1a del Mar).<\/p>\n<p>Las Cadenas &#8211; Estudiantes (Quilpu\u00e9).<\/p>\n<figure id=\"attachment_137797\" aria-describedby=\"caption-attachment-137797\" style=\"width: 698px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-137797\" src=\"http:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Libertad.jpg\" alt=\"Libertad de Guzmanes se meti\u00f3 en el selecto grupo de los 32 mejores equipos de la Copa de Campeones de mujeres. \" width=\"698\" height=\"302\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Libertad.jpg 698w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Libertad-300x130.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Libertad-150x65.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Libertad-696x301.jpg 696w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><figcaption id=\"caption-attachment-137797\" class=\"wp-caption-text\">Libertad de Guzmanes se meti\u00f3 en el selecto grupo de los 32 mejores equipos de la Copa de Campeones de mujeres.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Durante el fin de semana pasado se jugaron los partidos de revancha para confirmar el cuadro de los treinta y dos mejores equipos femeninos que compiten en la versi\u00f3n 2025 de la \u2018Copa de Campeones Femenina\u2019. Dentro de ese selecto grupo de conjuntos femeninos, sobresalen cuatro oncenas de nuestra zona, equipos que ahora y desde [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":137797,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-137796","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuatro equipos de la zona avanzaron al cuadro\u00a0de los dieciseisavos de final de la \u2018Orejona\u2019 femenina - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuatro equipos de la zona avanzaron al cuadro\u00a0de los dieciseisavos de final de la \u2018Orejona\u2019 femenina - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Durante el fin de semana pasado se jugaron los partidos de revancha para confirmar el cuadro de los treinta y dos mejores equipos femeninos que compiten en la versi\u00f3n 2025 de la \u2018Copa de Campeones Femenina\u2019. Dentro de ese selecto grupo de conjuntos femeninos, sobresalen cuatro oncenas de nuestra zona, equipos que ahora y desde [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-04T00:35:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Libertad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"698\" \/>\n\t<meta property=\"og:image:height\" content=\"302\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Cuatro equipos de la zona avanzaron al cuadro\u00a0de los dieciseisavos de final de la \u2018Orejona\u2019 femenina\",\"datePublished\":\"2025-06-04T00:35:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\\\/\"},\"wordCount\":230,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Libertad.jpg\",\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\\\/\",\"name\":\"Cuatro equipos de la zona avanzaron al cuadro\u00a0de los dieciseisavos de final de la \u2018Orejona\u2019 femenina - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Libertad.jpg\",\"datePublished\":\"2025-06-04T00:35:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Libertad.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Libertad.jpg\",\"width\":698,\"height\":302,\"caption\":\"Libertad de Guzmanes se meti\u00f3 en el selecto grupo de los 32 mejores equipos de la Copa de Campeones de mujeres.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuatro equipos de la zona avanzaron al cuadro\u00a0de los dieciseisavos de final de la \u2018Orejona\u2019 femenina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuatro equipos de la zona avanzaron al cuadro\u00a0de los dieciseisavos de final de la \u2018Orejona\u2019 femenina - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/","og_locale":"es_ES","og_type":"article","og_title":"Cuatro equipos de la zona avanzaron al cuadro\u00a0de los dieciseisavos de final de la \u2018Orejona\u2019 femenina - Diario El Trabajo","og_description":"Durante el fin de semana pasado se jugaron los partidos de revancha para confirmar el cuadro de los treinta y dos mejores equipos femeninos que compiten en la versi\u00f3n 2025 de la \u2018Copa de Campeones Femenina\u2019. Dentro de ese selecto grupo de conjuntos femeninos, sobresalen cuatro oncenas de nuestra zona, equipos que ahora y desde [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2025-06-04T00:35:08+00:00","og_image":[{"width":698,"height":302,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Libertad.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Cuatro equipos de la zona avanzaron al cuadro\u00a0de los dieciseisavos de final de la \u2018Orejona\u2019 femenina","datePublished":"2025-06-04T00:35:08+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/"},"wordCount":230,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Libertad.jpg","articleSection":["Deportes"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/","url":"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/","name":"Cuatro equipos de la zona avanzaron al cuadro\u00a0de los dieciseisavos de final de la \u2018Orejona\u2019 femenina - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Libertad.jpg","datePublished":"2025-06-04T00:35:08+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Libertad.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/Libertad.jpg","width":698,"height":302,"caption":"Libertad de Guzmanes se meti\u00f3 en el selecto grupo de los 32 mejores equipos de la Copa de Campeones de mujeres."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/cuatro-equipos-de-la-zona-avanzaron-al-cuadro-de-los-dieciseisavos-de-final-de-la-orejona-femenina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Cuatro equipos de la zona avanzaron al cuadro\u00a0de los dieciseisavos de final de la \u2018Orejona\u2019 femenina"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/137796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=137796"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/137796\/revisions"}],"predecessor-version":[{"id":137798,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/137796\/revisions\/137798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/137797"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=137796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=137796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=137796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}