{"id":138287,"date":"2025-06-29T21:46:50","date_gmt":"2025-06-30T00:46:50","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=138287"},"modified":"2025-06-29T21:46:50","modified_gmt":"2025-06-30T00:46:50","slug":"diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/","title":{"rendered":"Diputadas Barchiesi y Bravo impulsan proyecto para ordenar acceso a la educaci\u00f3n parvularia"},"content":{"rendered":"<ul>\n<li><strong>El proyecto de resoluci\u00f3n aprobado, pide al Ejecutivo establecer criterios claros de priorizaci\u00f3n para jardines infantiles, favoreciendo a ni\u00f1os chilenos y a hijos de residentes legales, ante el aumento de denuncias por exclusiones.-<\/strong><\/li>\n<\/ul>\n<p>La C\u00e1mara de Diputados aprob\u00f3 esta semana la solicitud de resoluci\u00f3n N\u00b0 1470, presentada por las diputadas <strong>Chiara Barchiesi <\/strong>y <strong>Marta Bravo<\/strong>, que pide al Presidente de la Rep\u00fablica dictar instrucciones al Ministerio de Educaci\u00f3n, Junji y Fundaci\u00f3n Integra para establecer mecanismos de priorizaci\u00f3n en el acceso a jardines infantiles y salas cuna, dando preferencia a ni\u00f1os chilenos y a hijos de padres con residencia legal en el pa\u00eds.<\/p>\n<p>La iniciativa surge tras casos como el ocurrido en Valpara\u00edso, donde un padre chileno fue informado que su hija no tendr\u00eda prioridad en un jard\u00edn infantil por el solo hecho de ser chilena. <em>\u00abLo que pedimos es puro sentido com\u00fan: que el Estado garantice primero el acceso a los ni\u00f1os chilenos y a quienes residen legalmente. Hoy, lamentablemente, eso no est\u00e1 ocurriendo\u00bb<\/em>, afirm\u00f3 la diputada Barchiesi.<\/p>\n<p>Durante la votaci\u00f3n, algunos diputados usaron la palabra en la sala para oponerse abiertamente a esta propuesta. Como record\u00f3 la diputada Barchiesi, no es la primera vez: ya presentaron una reserva de constitucionalidad contra un proyecto que buscaba priorizar a ni\u00f1os y j\u00f3venes chilenos en el sistema educativo. <em>\u00ab\u00bfD\u00f3nde pretende el gobierno de Boric que estudien los ni\u00f1os chilenos si no los priorizamos en nuestro propio pa\u00eds?\u00bb<\/em>, cuestion\u00f3.<\/p>\n<p>El texto aprobado en sala expone fundamentos sociales, jur\u00eddicos y administrativos para justificar la necesidad de orden en el acceso a prestaciones p\u00fablicas. Entre ellos, la presi\u00f3n que genera el incremento de la migraci\u00f3n irregular sobre los servicios p\u00fablicos, y la urgencia de evitar tensiones sociales derivadas de percepciones de injusticia en la distribuci\u00f3n de beneficios financiados con recursos del Estado.<\/p>\n<p>\u00ab<em>Lo que hemos impulsado es un llamado claro al Ejecutivo para que asuma su responsabilidad y establezca una pol\u00edtica p\u00fablica coherente con nuestra realidad social. Esta resoluci\u00f3n no excluye a nadie, pero s\u00ed prioriza el v\u00ednculo jur\u00eddico con el pa\u00eds\u00bb<\/em>, explic\u00f3 Marta Bravo, coautora del proyecto.<\/p>\n<p>Las diputadas esperan que el gobierno responda con la tramitaci\u00f3n de un reglamento o proyecto de ley que materialice esta priorizaci\u00f3n de forma clara y transparente.<\/p>\n<p>\u00ab<em>Hoy dimos una se\u00f1al de coherencia y justicia. Si el Gobierno de Boric realmente cree en el bien com\u00fan, debe escuchar lo que ha aprobado la C\u00e1mara. Porque si los ni\u00f1os chilenos no tienen espacio para estudiar en Chile, \u00bfd\u00f3nde pretende que estudien?\u00bb<\/em>, concluy\u00f3 Barchiesi.<\/p>\n<figure id=\"attachment_138288\" aria-describedby=\"caption-attachment-138288\" style=\"width: 698px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-138288\" src=\"http:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/jardin_infantil.jpg\" alt=\"Diputadas Barchiesi y Bravo, presentaron un proyecto para ordenar acceso a la educaci\u00f3n parvularia. (Imagen referencial:vitamina.cl).\" width=\"698\" height=\"421\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/jardin_infantil.jpg 698w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/jardin_infantil-300x181.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/jardin_infantil-696x420.jpg 696w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/jardin_infantil-150x90.jpg 150w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><figcaption id=\"caption-attachment-138288\" class=\"wp-caption-text\">Diputadas Barchiesi y Bravo, presentaron un proyecto para ordenar acceso a la educaci\u00f3n parvularia. (Imagen referencial:vitamina.cl).<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El proyecto de resoluci\u00f3n aprobado, pide al Ejecutivo establecer criterios claros de priorizaci\u00f3n para jardines infantiles, favoreciendo a ni\u00f1os chilenos y a hijos de residentes legales, ante el aumento de denuncias por exclusiones.- La C\u00e1mara de Diputados aprob\u00f3 esta semana la solicitud de resoluci\u00f3n N\u00b0 1470, presentada por las diputadas Chiara Barchiesi y Marta Bravo, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":138288,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-138287","post","type-post","status-publish","format-standard","has-post-thumbnail","category-comunidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diputadas Barchiesi y Bravo impulsan proyecto para ordenar acceso a la educaci\u00f3n parvularia - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diputadas Barchiesi y Bravo impulsan proyecto para ordenar acceso a la educaci\u00f3n parvularia - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"El proyecto de resoluci\u00f3n aprobado, pide al Ejecutivo establecer criterios claros de priorizaci\u00f3n para jardines infantiles, favoreciendo a ni\u00f1os chilenos y a hijos de residentes legales, ante el aumento de denuncias por exclusiones.- La C\u00e1mara de Diputados aprob\u00f3 esta semana la solicitud de resoluci\u00f3n N\u00b0 1470, presentada por las diputadas Chiara Barchiesi y Marta Bravo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-30T00:46:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/jardin_infantil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"698\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Diputadas Barchiesi y Bravo impulsan proyecto para ordenar acceso a la educaci\u00f3n parvularia\",\"datePublished\":\"2025-06-30T00:46:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\\\/\"},\"wordCount\":495,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/jardin_infantil.jpg\",\"articleSection\":[\"Comunidad\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\\\/\",\"name\":\"Diputadas Barchiesi y Bravo impulsan proyecto para ordenar acceso a la educaci\u00f3n parvularia - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/jardin_infantil.jpg\",\"datePublished\":\"2025-06-30T00:46:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/jardin_infantil.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/jardin_infantil.jpg\",\"width\":698,\"height\":421,\"caption\":\"Diputadas Barchiesi y Bravo, presentaron un proyecto para ordenar acceso a la educaci\u00f3n parvularia. (Imagen referencial:vitamina.cl).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diputadas Barchiesi y Bravo impulsan proyecto para ordenar acceso a la educaci\u00f3n parvularia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diputadas Barchiesi y Bravo impulsan proyecto para ordenar acceso a la educaci\u00f3n parvularia - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/","og_locale":"es_ES","og_type":"article","og_title":"Diputadas Barchiesi y Bravo impulsan proyecto para ordenar acceso a la educaci\u00f3n parvularia - Diario El Trabajo","og_description":"El proyecto de resoluci\u00f3n aprobado, pide al Ejecutivo establecer criterios claros de priorizaci\u00f3n para jardines infantiles, favoreciendo a ni\u00f1os chilenos y a hijos de residentes legales, ante el aumento de denuncias por exclusiones.- La C\u00e1mara de Diputados aprob\u00f3 esta semana la solicitud de resoluci\u00f3n N\u00b0 1470, presentada por las diputadas Chiara Barchiesi y Marta Bravo, [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2025-06-30T00:46:50+00:00","og_image":[{"width":698,"height":421,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/jardin_infantil.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Diputadas Barchiesi y Bravo impulsan proyecto para ordenar acceso a la educaci\u00f3n parvularia","datePublished":"2025-06-30T00:46:50+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/"},"wordCount":495,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/jardin_infantil.jpg","articleSection":["Comunidad"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/","url":"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/","name":"Diputadas Barchiesi y Bravo impulsan proyecto para ordenar acceso a la educaci\u00f3n parvularia - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/jardin_infantil.jpg","datePublished":"2025-06-30T00:46:50+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/jardin_infantil.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/06\/jardin_infantil.jpg","width":698,"height":421,"caption":"Diputadas Barchiesi y Bravo, presentaron un proyecto para ordenar acceso a la educaci\u00f3n parvularia. (Imagen referencial:vitamina.cl)."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/diputadas-barchiesi-y-bravo-impulsan-proyecto-para-ordenar-acceso-a-la-educacion-parvularia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Diputadas Barchiesi y Bravo impulsan proyecto para ordenar acceso a la educaci\u00f3n parvularia"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/138287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=138287"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/138287\/revisions"}],"predecessor-version":[{"id":138289,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/138287\/revisions\/138289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/138288"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=138287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=138287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=138287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}