{"id":138739,"date":"2025-07-21T21:30:43","date_gmt":"2025-07-22T00:30:43","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=138739"},"modified":"2025-07-21T21:30:43","modified_gmt":"2025-07-22T00:30:43","slug":"isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/","title":{"rendered":"Isidora Torres: La \u00fanica mujer que hoy surca los cielos del Aconcagua desde el Club A\u00e9reo de San Felipe"},"content":{"rendered":"<ul>\n<li><strong>Con determinaci\u00f3n y pasi\u00f3n por volar, Ia joven ha marcado un hito en la historia del aer\u00f3dromo sanfelipe\u00f1o.-<\/strong><\/li>\n<\/ul>\n<p>Desde su cabina en el aire hasta los micr\u00f3fonos de una radio local, <strong>Isidora Torres Peralta<\/strong> vive intensamente. A sus 26 a\u00f1os de edad, la multifac\u00e9tica sanfelipe\u00f1a se encuentra a punto de obtener su licencia de piloto privado, siendo actualmente la \u00fanica mujer que forma parte del Club A\u00e9reo de San Felipe, con sede en el aer\u00f3dromo V\u00edctor Laf\u00f3n, fundado en 1942.<\/p>\n<p>Su nombre ya es parte de la historia del club, que no contaba con una mujer entre sus pilotos o alumnas desde los a\u00f1os 80. <em>\u00abS\u00ed, soy la \u00fanica mujer actualmente en el Club A\u00e9reo de San Felipe, la \u00fanica alumna y la \u00fanica piloto aqu\u00ed en el club a\u00e9reo\u00bb,<\/em> confirm\u00f3.<\/p>\n<p>Aunque podr\u00eda parecer una haza\u00f1a reciente, su incursi\u00f3n en el mundo de la aviaci\u00f3n comenz\u00f3 en 2021, a\u00f1o en que ingres\u00f3 al club. <em>\u00abEntr\u00e9 en agosto del 2021, fecha exacta no me acuerdo, s\u00e9 que fue un veintitanto&#8230; y cuando empec\u00e9 a volar fue como entre Navidad y A\u00f1o Nuevo de ese mismo a\u00f1o\u00bb,<\/em> record\u00f3.<\/p>\n<p>M\u00e1s all\u00e1 del vuelo y las pistas de aterrizaje, Isidora reparte su tiempo entre la Radio Lovely, donde conduce los programas \u2018Mujeres arriba\u2019 y \u2018Magazine Lovely\u2019; su profesi\u00f3n como dise\u00f1adora de alta costura, actualmente cursando un diplomado en la materia; su trabajo en el restaurante Rinc\u00f3n Clandestino Enjoy; y un podcast de turismo llamado \u2018C\u00e1mara Travels\u2019.<\/p>\n<p>Uno de los momentos m\u00e1s emotivos en su camino como piloto ocurri\u00f3 el 26 de abril de 2024, cuando realiz\u00f3 su primer vuelo sola en un Cessna 150, matr\u00edcula Kilo Fox Alfa (KFA), avi\u00f3n que ahora lleva tatuado en su brazo como s\u00edmbolo de ese hito. M\u00e1s all\u00e1 del desaf\u00edo t\u00e9cnico, fue una experiencia profundamente personal.<\/p>\n<p>\u00ab<em>En ese momento mi entrenador me dice vas a hacer tu primer vuelo sola y est\u00e1bamos solamente los dos. Me dice \u2018\u00bfest\u00e1s lista?, yo me voy a bajar y en estos momentos se va a subir tu pap\u00e1\u2019. Te juro que cuando me dice eso, me cierra la puerta y me puse a llorar, y yo dije: \u2018\u00bflo hago o me rindo, me devuelvo y digo no, no lo voy a hacer? Y ah\u00ed fue cuando yo dije \u2018no, s\u00ed lo voy a hacer. Estoy lista, es mi momento\u2019\u00bb,<\/em> relat\u00f3 Isidora, con la emoci\u00f3n a\u00fan palpable en sus palabras.<\/p>\n<p>El vuelo fue un tributo al amor y apoyo que siempre recibi\u00f3 de su padre, fallecido en febrero de 2023. <em>\u00abCuando toqu\u00e9 tierra, te juro que grit\u00e9 y lo \u00fanico que dec\u00eda era, \u2018gracias, pap\u00e1\u2019\u00bb<\/em>, expres\u00f3.<\/p>\n<p>Isidora se ha formado en el propio club, donde los socios imparten las clases te\u00f3ricas, generalmente de manera online. La instrucci\u00f3n pr\u00e1ctica ha estado a cargo de <strong>Fernando Tapia<\/strong>, conocido como \u2018Torniquete Carajo\u2019, presidente del Club A\u00e9reo y piloto acrob\u00e1tico, con quien ha desarrollado una estrecha relaci\u00f3n de confianza.<\/p>\n<p>\u00ab<em>Gracias a Fernando, la verdad es que un vuelo result\u00f3 bien&#8230; por la experiencia que \u00e9l tiene, la expertise realmente y la confianza que nos tenemos\u00bb,<\/em> afirm\u00f3, haciendo alusi\u00f3n a un vuelo de navegaci\u00f3n reciente que puso a prueba sus habilidades y temple.<\/p>\n<p>Parte de su entrenamiento ha incluido vuelos de navegaci\u00f3n fuera del valle, siendo uno de los m\u00e1s significativos el que la llev\u00f3 hasta Chill\u00e1n, pasando por Talca y Villa Baviera.<em> \u00abFue realmente entretenido, de verdad, fue muy entretenido y pasaron hartas cosas\u00bb,<\/em> coment\u00f3.<\/p>\n<p>El regreso no fue sencillo<em>. \u00abCuando est\u00e1bamos acerc\u00e1ndonos a Curic\u00f3 estaba muy nublado, pero tan nublado que no se ve\u00eda nada&#8230; un techo de nube y un suelo de nube, entonces no ve\u00edamos nada, nada, nada\u00bb<\/em>. Con esfuerzo, apoyo t\u00e9cnico y entereza, lograron regresar a San Felipe. <em>\u00abFue sumamente dif\u00edcil&#8230; pero fue s\u00faper entretenido y realmente fue una experiencia maravillosa\u00bb,<\/em> sostuvo.<\/p>\n<p>El camino de Isidora en el mundo de la aviaci\u00f3n no ha estado exento de pausas y momentos de duda. En 2023, tras la muerte de su padre, pens\u00f3 seriamente en dejarlo todo. Sin embargo, gracias al empuje de su madre, amigas y su propia determinaci\u00f3n, retom\u00f3 el curso.<\/p>\n<p>Hoy vuela con un prop\u00f3sito. En cada despegue, en cada aterrizaje, lleva consigo algo m\u00e1s que los controles de un avi\u00f3n. Lleva una historia de esfuerzo, amor, p\u00e9rdida y superaci\u00f3n. Y aunque es la \u00fanica mujer entre los cielos de San Felipe, no parece que eso la limite.<\/p>\n<p>Quienes deseen saber m\u00e1s sobre ella pueden encontrarla en Instagram como <strong>@izzysoffi<\/strong>.<\/p>\n<figure id=\"attachment_138742\" aria-describedby=\"caption-attachment-138742\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-138742\" src=\"http:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-2.jpg\" alt=\"La multifac\u00e9tica sanfelipe\u00f1a se encuentra a punto de obtener su licencia de piloto privado.\" width=\"699\" height=\"353\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-2.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-2-300x152.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-2-150x76.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-2-696x351.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-138742\" class=\"wp-caption-text\">La multifac\u00e9tica sanfelipe\u00f1a se encuentra a punto de obtener su licencia de piloto privado.<\/figcaption><\/figure>\n<figure id=\"attachment_138741\" aria-describedby=\"caption-attachment-138741\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-138741\" src=\"http:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-1.jpg\" alt=\"Isidora Torres Peralta, piloto en formaci\u00f3n del Club A\u00e9reo de San Felipe.\" width=\"699\" height=\"525\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-1.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-1-300x225.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-1-559x420.jpg 559w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-1-80x60.jpg 80w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-1-150x113.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-1-696x523.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-138741\" class=\"wp-caption-text\">Isidora Torres Peralta, piloto en formaci\u00f3n del Club A\u00e9reo de San Felipe.<\/figcaption><\/figure>\n<figure id=\"attachment_138740\" aria-describedby=\"caption-attachment-138740\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-138740\" src=\"http:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-3.jpg\" alt=\"Vista de la Cuesta Chacabuco capturada por Isidora en uno de sus vuelos.\" width=\"699\" height=\"933\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-3.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-3-225x300.jpg 225w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-3-315x420.jpg 315w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-3-150x200.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-3-300x400.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-3-696x929.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-138740\" class=\"wp-caption-text\">Vista de la Cuesta Chacabuco capturada por Isidora en uno de sus vuelos.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Con determinaci\u00f3n y pasi\u00f3n por volar, Ia joven ha marcado un hito en la historia del aer\u00f3dromo sanfelipe\u00f1o.- Desde su cabina en el aire hasta los micr\u00f3fonos de una radio local, Isidora Torres Peralta vive intensamente. A sus 26 a\u00f1os de edad, la multifac\u00e9tica sanfelipe\u00f1a se encuentra a punto de obtener su licencia de piloto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":138741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-138739","post","type-post","status-publish","format-standard","has-post-thumbnail","category-comunidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Isidora Torres: La \u00fanica mujer que hoy surca los cielos del Aconcagua desde el Club A\u00e9reo de San Felipe - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isidora Torres: La \u00fanica mujer que hoy surca los cielos del Aconcagua desde el Club A\u00e9reo de San Felipe - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Con determinaci\u00f3n y pasi\u00f3n por volar, Ia joven ha marcado un hito en la historia del aer\u00f3dromo sanfelipe\u00f1o.- Desde su cabina en el aire hasta los micr\u00f3fonos de una radio local, Isidora Torres Peralta vive intensamente. A sus 26 a\u00f1os de edad, la multifac\u00e9tica sanfelipe\u00f1a se encuentra a punto de obtener su licencia de piloto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-22T00:30:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"699\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Isidora Torres: La \u00fanica mujer que hoy surca los cielos del Aconcagua desde el Club A\u00e9reo de San Felipe\",\"datePublished\":\"2025-07-22T00:30:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\\\/\"},\"wordCount\":878,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/piloto-1.jpg\",\"articleSection\":[\"Comunidad\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\\\/\",\"name\":\"Isidora Torres: La \u00fanica mujer que hoy surca los cielos del Aconcagua desde el Club A\u00e9reo de San Felipe - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/piloto-1.jpg\",\"datePublished\":\"2025-07-22T00:30:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/piloto-1.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/piloto-1.jpg\",\"width\":699,\"height\":525,\"caption\":\"Isidora Torres Peralta, piloto en formaci\u00f3n del Club A\u00e9reo de San Felipe.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Isidora Torres: La \u00fanica mujer que hoy surca los cielos del Aconcagua desde el Club A\u00e9reo de San Felipe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Isidora Torres: La \u00fanica mujer que hoy surca los cielos del Aconcagua desde el Club A\u00e9reo de San Felipe - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/","og_locale":"es_ES","og_type":"article","og_title":"Isidora Torres: La \u00fanica mujer que hoy surca los cielos del Aconcagua desde el Club A\u00e9reo de San Felipe - Diario El Trabajo","og_description":"Con determinaci\u00f3n y pasi\u00f3n por volar, Ia joven ha marcado un hito en la historia del aer\u00f3dromo sanfelipe\u00f1o.- Desde su cabina en el aire hasta los micr\u00f3fonos de una radio local, Isidora Torres Peralta vive intensamente. A sus 26 a\u00f1os de edad, la multifac\u00e9tica sanfelipe\u00f1a se encuentra a punto de obtener su licencia de piloto [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2025-07-22T00:30:43+00:00","og_image":[{"width":699,"height":525,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-1.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Isidora Torres: La \u00fanica mujer que hoy surca los cielos del Aconcagua desde el Club A\u00e9reo de San Felipe","datePublished":"2025-07-22T00:30:43+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/"},"wordCount":878,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-1.jpg","articleSection":["Comunidad"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/","url":"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/","name":"Isidora Torres: La \u00fanica mujer que hoy surca los cielos del Aconcagua desde el Club A\u00e9reo de San Felipe - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-1.jpg","datePublished":"2025-07-22T00:30:43+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-1.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/piloto-1.jpg","width":699,"height":525,"caption":"Isidora Torres Peralta, piloto en formaci\u00f3n del Club A\u00e9reo de San Felipe."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/isidora-torres-la-unica-mujer-que-hoy-surca-los-cielos-del-aconcagua-desde-el-club-aereo-de-san-felipe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Isidora Torres: La \u00fanica mujer que hoy surca los cielos del Aconcagua desde el Club A\u00e9reo de San Felipe"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/138739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=138739"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/138739\/revisions"}],"predecessor-version":[{"id":138743,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/138739\/revisions\/138743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/138741"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=138739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=138739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=138739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}