{"id":138826,"date":"2025-07-27T21:23:25","date_gmt":"2025-07-28T00:23:25","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=138826"},"modified":"2025-07-27T21:23:25","modified_gmt":"2025-07-28T00:23:25","slug":"salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/","title":{"rendered":"Salud advierte nueva alza en consultas por Virus respiratorio sincicial para esta semana"},"content":{"rendered":"<ul>\n<li><strong>Proyecciones indican que en los presentes siete d\u00edas deber\u00eda experimentarse un crecimiento de cuadros respiratorios.\u2013<\/strong><\/li>\n<\/ul>\n<p>Una nueva semana de alza de casos de enfermedades respiratorias es la que se espera a nivel nacional, y obviamente, la zona de Aconcagua no es la excepci\u00f3n. Seg\u00fan las proyecciones entregadas desde el Ministerio de Salud (Minsal), se espera que durante estos pr\u00f3ximos siete d\u00edas se experimente un crecimiento de las consultas por estas enfermedades, sobre todo, de Virus sincicial respiratorio.<\/p>\n<p>Al respecto, <strong>Valeria C\u00e1diz<\/strong>, referente de la red de urgencia y epidemiolog\u00eda del Servicio de Salud Aconcagua (SSA), se\u00f1al\u00f3 que <em>\u00abel SSA en las \u00faltimas semanas ha observado un aumento en la demanda de atenci\u00f3n de urgencia, no solo con respecto a las consultas respiratorias, sino que por todas las cusas\u00bb<\/em>.<\/p>\n<p>En cuanto a c\u00f3mo ha sido la realidad de nuestra zona en las \u00faltimas semanas en cuanto a las enfermedades respiratorias, C\u00e1diz coment\u00f3 que <em>\u00abvemos que en pacientes adultos han aumentado m\u00e1s marcadamente las consultas; no obstante, en pacientes pedi\u00e1tricos, las consultas se han concentrado a nivel hospitalario y esto da cuenta de cuadros respiratorios de mediana y mayor complejidad\u00bb<\/em>.<\/p>\n<p>Asimismo, y en relaci\u00f3n al requerimiento de hospitalizaciones y lo que se espera para los pr\u00f3ximos d\u00edas, Valeria C\u00e1diz indic\u00f3 que <em>\u00abactualmente se duplicaron las hospitalizaciones por causas respiratorias en ni\u00f1os, lo cual es un indicador que tenemos que seguir<\/em>, <em>porque seg\u00fan las proyecciones que han hecho desde el Ministerio de Salud. La pr\u00f3xima semana se podr\u00eda experimentar un nuevo peak de aumento en la demanda y tambi\u00e9n en hospitalizaciones, principalmente, causados por el Virus respiratorio sincicial en pacientes pedi\u00e1tricos\u00bb<\/em>.<\/p>\n<p>Es por esto, que desde salud se ha preparado y dise\u00f1ado una estrategia para hacer frente al alza de consultas por casos de enfermedades respiratorias, <em>\u00abpreparar un plan de abordaje para este aumento de demanda y aumento de gravedad en los pacientes que se est\u00e1n hospitalizando para poder reconvertir camas en caso de ser necesario y que las redes est\u00e9n preparadas para hacer frente a este escenario que se espera se desarrolle\u00bb<\/em>, asegur\u00f3.<\/p>\n<p>Finalmente, la referente de la red de urgencia y epidemiolog\u00eda del Servicio de Salud Aconcagua, precis\u00f3 que las proyecciones indican que, ya durante el pr\u00f3ximo mes de agosto, este tipo de enfermedades comenzar\u00edan a disminuir en el pa\u00eds.<\/p>\n<p>\u00ab<em>Seg\u00fan las proyecciones deber\u00eda, una vez que pasemos la pr\u00f3xima semana que es la semana epidemiol\u00f3gica 31; deber\u00edan ir disminuyendo las consultas por esta causa, sin embargo, hay que seguir monitoreando la circulaci\u00f3n viral.<\/em><\/p>\n<p>\u00ab<em>Hoy vemos en la red que el 80% de los virus respiratorios que se han detectado en pacientes hospitalizados, corresponde al Virus respiratorio sincicial, entonces, es importante que tambi\u00e9n, adicionalmente a las proyecciones que hay desde el nivel central, tambi\u00e9n revisemos qu\u00e9 ocurre de manera local para poder ir implementando los planes para fortalecer la red\u00bb<\/em>, cerr\u00f3.<\/p>\n<figure id=\"attachment_138827\" aria-describedby=\"caption-attachment-138827\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-138827\" src=\"http:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Valeria-Cadiz-SSA.jpg\" alt=\"Valeria C\u00e1diz, referente red de urgencia e epidemiolog\u00eda del Servicio de Salud Aconcagua. \" width=\"699\" height=\"469\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Valeria-Cadiz-SSA.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Valeria-Cadiz-SSA-300x201.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Valeria-Cadiz-SSA-626x420.jpg 626w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Valeria-Cadiz-SSA-150x101.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Valeria-Cadiz-SSA-696x467.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-138827\" class=\"wp-caption-text\">Valeria C\u00e1diz, referente red de urgencia e epidemiolog\u00eda del Servicio de Salud Aconcagua.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Proyecciones indican que en los presentes siete d\u00edas deber\u00eda experimentarse un crecimiento de cuadros respiratorios.\u2013 Una nueva semana de alza de casos de enfermedades respiratorias es la que se espera a nivel nacional, y obviamente, la zona de Aconcagua no es la excepci\u00f3n. Seg\u00fan las proyecciones entregadas desde el Ministerio de Salud (Minsal), se espera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":138827,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-138826","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cronica-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salud advierte nueva alza en consultas por Virus respiratorio sincicial para esta semana - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salud advierte nueva alza en consultas por Virus respiratorio sincicial para esta semana - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Proyecciones indican que en los presentes siete d\u00edas deber\u00eda experimentarse un crecimiento de cuadros respiratorios.\u2013 Una nueva semana de alza de casos de enfermedades respiratorias es la que se espera a nivel nacional, y obviamente, la zona de Aconcagua no es la excepci\u00f3n. Seg\u00fan las proyecciones entregadas desde el Ministerio de Salud (Minsal), se espera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-28T00:23:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Valeria-Cadiz-SSA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"699\" \/>\n\t<meta property=\"og:image:height\" content=\"469\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Salud advierte nueva alza en consultas por Virus respiratorio sincicial para esta semana\",\"datePublished\":\"2025-07-28T00:23:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\\\/\"},\"wordCount\":542,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Valeria-Cadiz-SSA.jpg\",\"articleSection\":[\"Cr\u00f3nica\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\\\/\",\"name\":\"Salud advierte nueva alza en consultas por Virus respiratorio sincicial para esta semana - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Valeria-Cadiz-SSA.jpg\",\"datePublished\":\"2025-07-28T00:23:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Valeria-Cadiz-SSA.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Valeria-Cadiz-SSA.jpg\",\"width\":699,\"height\":469,\"caption\":\"Valeria C\u00e1diz, referente red de urgencia e epidemiolog\u00eda del Servicio de Salud Aconcagua.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salud advierte nueva alza en consultas por Virus respiratorio sincicial para esta semana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salud advierte nueva alza en consultas por Virus respiratorio sincicial para esta semana - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/","og_locale":"es_ES","og_type":"article","og_title":"Salud advierte nueva alza en consultas por Virus respiratorio sincicial para esta semana - Diario El Trabajo","og_description":"Proyecciones indican que en los presentes siete d\u00edas deber\u00eda experimentarse un crecimiento de cuadros respiratorios.\u2013 Una nueva semana de alza de casos de enfermedades respiratorias es la que se espera a nivel nacional, y obviamente, la zona de Aconcagua no es la excepci\u00f3n. Seg\u00fan las proyecciones entregadas desde el Ministerio de Salud (Minsal), se espera [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2025-07-28T00:23:25+00:00","og_image":[{"width":699,"height":469,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Valeria-Cadiz-SSA.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Salud advierte nueva alza en consultas por Virus respiratorio sincicial para esta semana","datePublished":"2025-07-28T00:23:25+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/"},"wordCount":542,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Valeria-Cadiz-SSA.jpg","articleSection":["Cr\u00f3nica"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/","url":"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/","name":"Salud advierte nueva alza en consultas por Virus respiratorio sincicial para esta semana - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Valeria-Cadiz-SSA.jpg","datePublished":"2025-07-28T00:23:25+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Valeria-Cadiz-SSA.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Valeria-Cadiz-SSA.jpg","width":699,"height":469,"caption":"Valeria C\u00e1diz, referente red de urgencia e epidemiolog\u00eda del Servicio de Salud Aconcagua."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/salud-advierte-nueva-alza-en-consultas-por-virus-respiratorio-sincicial-para-esta-semana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Salud advierte nueva alza en consultas por Virus respiratorio sincicial para esta semana"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/138826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=138826"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/138826\/revisions"}],"predecessor-version":[{"id":138828,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/138826\/revisions\/138828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/138827"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=138826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=138826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=138826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}