{"id":138887,"date":"2025-07-29T20:59:34","date_gmt":"2025-07-29T23:59:34","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=138887"},"modified":"2025-07-29T20:59:34","modified_gmt":"2025-07-29T23:59:34","slug":"fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/","title":{"rendered":"\u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 particip\u00f3 en Fiesta de la Virgen del Carmen en Maip\u00fa"},"content":{"rendered":"<ul>\n<li><strong>Agrupaci\u00f3n fue la \u00fanica representante de la Di\u00f3cesis de San Felipe en la celebraci\u00f3n realizada en el Templo Votivo.-<\/strong><\/li>\n<\/ul>\n<p>Una emotiva y significativa participaci\u00f3n tuvo la \u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 de San Felipe en la Fiesta de la Virgen del Carmen, realizada el pasado domingo 27 de julio en el Templo Votivo de Maip\u00fa. El grupo, perteneciente a la parroquia Nuestra Se\u00f1ora del Rosario de Andacollo, fue parte de esta tradicional celebraci\u00f3n organizada por la Asociaci\u00f3n Metropolitana de Bailes Religiosos (AMBAR), que reuni\u00f3 a 24 agrupaciones provenientes de distintas comunas de Santiago, Rancagua y San Felipe.<\/p>\n<p>La Fraternidad sanfelipe\u00f1a fue la \u00fanica representante de la Di\u00f3cesis de San Felipe en este importante encuentro de fe mariana, destacando por su devoci\u00f3n, entusiasmo y compromiso con las tradiciones religiosas.<\/p>\n<p>La jornada comenz\u00f3 con los saludos a la Virgen del Carmen por parte de los distintos bailes participantes, seguida por la misa central celebrada en el hist\u00f3rico Templo Votivo. Posteriormente, se realiz\u00f3 una procesi\u00f3n por las calles de Maip\u00fa, acompa\u00f1ada por danzas, m\u00fasica y el fervor de cientos de fieles que rindieron homenaje a la Patrona de Chile.<\/p>\n<p>Para la \u2018Fraternidad Virgen del Rosario de Andacollo\u2019 de San Felipe, esta fue una experiencia inolvidable, ya que se trat\u00f3 de su primera participaci\u00f3n en una celebraci\u00f3n religiosa de tal magnitud, a tan solo diez meses desde su fundaci\u00f3n. La participaci\u00f3n marc\u00f3 un hito en la historia de la agrupaci\u00f3n, ya que compartieron bailes de larga trayectoria y vivieron momentos muy especiales que fortalecieron su fe y compromiso.<\/p>\n<p>La delegaci\u00f3n sanfelipe\u00f1a agradeci\u00f3 profundamente a cada uno de sus integrantes, apoderados y colaboradores, destacando el esfuerzo y dedicaci\u00f3n que han mantenido semana a semana para dar vida a este proyecto comunitario y espiritual. Ante ellos, expresaron que su constancia, alegr\u00eda y devoci\u00f3n son el motor que impulsa a la fraternidad a seguir creciendo y dejando huella en cada celebraci\u00f3n.<\/p>\n<p>Finalmente, extendieron una cordial invitaci\u00f3n a todas las personas que deseen integrarse al grupo, ya sea como bailarines o m\u00fasicos. No se requieren conocimientos previos, solo las ganas de aprender y servir a la Virgen.<\/p>\n<p>Los interesados pueden contactarse al tel\u00e9fono de la parroquia <strong>+56 9 3188 1969<\/strong> (de lunes a viernes entre 09:00 y 13:00; y de 13:30 a 17:00 horas), o directamente con <strong>Ricardo<\/strong>, encargado del grupo, al <strong>+56 9 3419 4520<\/strong>. Tambi\u00e9n, se reciben consultas al correo electr\u00f3nico: fraternidad.virgende andacollo.sf@gmail.com.<\/p>\n<figure id=\"attachment_138888\" aria-describedby=\"caption-attachment-138888\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-138888\" src=\"http:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-3.jpg\" alt=\"La agrupaci\u00f3n sanfelipe\u00f1a danzando durante la celebraci\u00f3n en honor a la Virgen del Carmen.\" width=\"699\" height=\"374\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-3.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-3-300x161.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-3-150x80.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-3-696x372.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-138888\" class=\"wp-caption-text\">La agrupaci\u00f3n sanfelipe\u00f1a danzando durante la celebraci\u00f3n en honor a la Virgen del Carmen.<\/figcaption><\/figure>\n<figure id=\"attachment_138889\" aria-describedby=\"caption-attachment-138889\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-138889\" src=\"http:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-1.jpg\" alt=\"Parte de los integrantes de la Fraternidad Religiosa Virgen del Rosario de Andacollo de San Felipe, durante su participaci\u00f3n en la Fiesta de la Virgen del Carmen en Maip\u00fa.\" width=\"699\" height=\"409\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-1.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-1-300x176.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-1-150x88.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-1-696x407.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-138889\" class=\"wp-caption-text\">Parte de los integrantes de la Fraternidad Religiosa Virgen del Rosario de Andacollo de San Felipe, durante su participaci\u00f3n en la Fiesta de la Virgen del Carmen en Maip\u00fa.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Agrupaci\u00f3n fue la \u00fanica representante de la Di\u00f3cesis de San Felipe en la celebraci\u00f3n realizada en el Templo Votivo.- Una emotiva y significativa participaci\u00f3n tuvo la \u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 de San Felipe en la Fiesta de la Virgen del Carmen, realizada el pasado domingo 27 de julio en el Templo Votivo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":138889,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-138887","post","type-post","status-publish","format-standard","has-post-thumbnail","category-comunidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 particip\u00f3 en Fiesta de la Virgen del Carmen en Maip\u00fa - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 particip\u00f3 en Fiesta de la Virgen del Carmen en Maip\u00fa - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Agrupaci\u00f3n fue la \u00fanica representante de la Di\u00f3cesis de San Felipe en la celebraci\u00f3n realizada en el Templo Votivo.- Una emotiva y significativa participaci\u00f3n tuvo la \u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 de San Felipe en la Fiesta de la Virgen del Carmen, realizada el pasado domingo 27 de julio en el Templo Votivo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-29T23:59:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"699\" \/>\n\t<meta property=\"og:image:height\" content=\"409\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"\u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 particip\u00f3 en Fiesta de la Virgen del Carmen en Maip\u00fa\",\"datePublished\":\"2025-07-29T23:59:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\\\/\"},\"wordCount\":498,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Fraternidad-Andacollo-1.jpg\",\"articleSection\":[\"Comunidad\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\\\/\",\"name\":\"\u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 particip\u00f3 en Fiesta de la Virgen del Carmen en Maip\u00fa - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Fraternidad-Andacollo-1.jpg\",\"datePublished\":\"2025-07-29T23:59:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Fraternidad-Andacollo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Fraternidad-Andacollo-1.jpg\",\"width\":699,\"height\":409,\"caption\":\"Parte de los integrantes de la Fraternidad Religiosa Virgen del Rosario de Andacollo de San Felipe, durante su participaci\u00f3n en la Fiesta de la Virgen del Carmen en Maip\u00fa.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 particip\u00f3 en Fiesta de la Virgen del Carmen en Maip\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 particip\u00f3 en Fiesta de la Virgen del Carmen en Maip\u00fa - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/","og_locale":"es_ES","og_type":"article","og_title":"\u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 particip\u00f3 en Fiesta de la Virgen del Carmen en Maip\u00fa - Diario El Trabajo","og_description":"Agrupaci\u00f3n fue la \u00fanica representante de la Di\u00f3cesis de San Felipe en la celebraci\u00f3n realizada en el Templo Votivo.- Una emotiva y significativa participaci\u00f3n tuvo la \u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 de San Felipe en la Fiesta de la Virgen del Carmen, realizada el pasado domingo 27 de julio en el Templo Votivo [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2025-07-29T23:59:34+00:00","og_image":[{"width":699,"height":409,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-1.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"\u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 particip\u00f3 en Fiesta de la Virgen del Carmen en Maip\u00fa","datePublished":"2025-07-29T23:59:34+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/"},"wordCount":498,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-1.jpg","articleSection":["Comunidad"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/","url":"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/","name":"\u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 particip\u00f3 en Fiesta de la Virgen del Carmen en Maip\u00fa - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-1.jpg","datePublished":"2025-07-29T23:59:34+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-1.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/07\/Fraternidad-Andacollo-1.jpg","width":699,"height":409,"caption":"Parte de los integrantes de la Fraternidad Religiosa Virgen del Rosario de Andacollo de San Felipe, durante su participaci\u00f3n en la Fiesta de la Virgen del Carmen en Maip\u00fa."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/fraternidad-religiosa-virgen-del-rosario-de-andacollo-participo-en-fiesta-de-la-virgen-del-carmen-en-maipu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"\u2018Fraternidad Religiosa Virgen del Rosario de Andacollo\u2019 particip\u00f3 en Fiesta de la Virgen del Carmen en Maip\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/138887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=138887"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/138887\/revisions"}],"predecessor-version":[{"id":138890,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/138887\/revisions\/138890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/138889"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=138887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=138887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=138887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}