{"id":139366,"date":"2025-08-20T21:40:07","date_gmt":"2025-08-21T00:40:07","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=139366"},"modified":"2025-08-20T21:40:07","modified_gmt":"2025-08-21T00:40:07","slug":"escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/","title":{"rendered":"Escuela U. de Chile San Felipe categor\u00eda 2016 se corona campeona nacional"},"content":{"rendered":"<ul>\n<li><strong>Ahora se encuentran disputando el torneo de Iniciaci\u00f3n ANFP y esperan con ansias el gran desaf\u00edo internacional: la Miami Cup 2026.-<\/strong><\/li>\n<\/ul>\n<p>Un verdadero orgullo para San Felipe es lo que logr\u00f3 la categor\u00eda 2016 de la Escuela de F\u00fatbol Universidad de Chile San Felipe, que el pasado 15 y 16 de agosto se coron\u00f3 campeona nacional en el encuentro de escuelas oficiales de la \u2018U\u2019, realizado en el complejo deportivo Caden, en la comuna de Pudahuel, Santiago.<\/p>\n<p>En el certamen participaron m\u00e1s de 2.300 ni\u00f1os de todo el pa\u00eds en distintas categor\u00edas. En la definici\u00f3n, los peque\u00f1os azules de San Felipe vencieron por 2-1 a la filial de Macul, tras una semifinal de infarto que se resolvi\u00f3 desde los lanzamientos penales.<\/p>\n<p>\u00ab<em>Fue un torneo muy emocionante, los ni\u00f1os dejaron todo en la cancha. En la final partimos perdiendo, pero se supieron sobreponer y lo dieron vuelta. Fue realmente una haza\u00f1a\u00bb,<\/em> destac\u00f3 la directora de la escuela, <strong>Katherine Reyes<\/strong>.<\/p>\n<p>Entre los jugadores m\u00e1s destacados de la final, estuvieron <strong>Pablo Elgueta<\/strong>, <strong>Tom\u00e1s Ort\u00edz<\/strong> y <strong>Santiago Laurel<\/strong>, todos pertenecientes al Valle de Aconcagua. Junto a ellos, el resto del plantel -once ni\u00f1os en total- proviene de distintas comunas de Santiago, conformando un equipo que mezcla talento local y capitalino.<\/p>\n<p>La categor\u00eda es dirigida por el profesor <strong>Mat\u00edas Figueroa<\/strong>, exfutbolista profesional que milit\u00f3 en Santiago Wanderers. <em>\u00abMat\u00edas lleva cinco a\u00f1os trabajando con nosotros, tiene una gran trayectoria en el f\u00fatbol formativo y ha sabido transmitir valores y disciplina a los ni\u00f1os\u00bb,<\/em> resalt\u00f3 Reyes.<\/p>\n<p>Actualmente, el equipo ya compite en el torneo de Iniciaci\u00f3n ANFP, donde acumula 20 fechas disputadas con solo cinco derrotas. <em>\u00abNuestro proyecto busca ser una vitrina para que los ni\u00f1os puedan proyectarse a equipos profesionales. La propia Universidad de Chile se lleva a nuestros mejores jugadores\u00bb,<\/em> explic\u00f3 la directora.<\/p>\n<p>El pr\u00f3ximo gran desaf\u00edo es la Miami Cup 2026, certamen internacional para el cual ya se preparan.<em> \u00abEstamos trabajando duro, participando en torneos de alta competencia y realizando pruebas de jugadores. No buscamos solo talentos extraordinarios, sino ni\u00f1os que tengan ganas y que podamos perfeccionar en lo f\u00edsico, motriz y t\u00e9cnico\u00bb,<\/em> detall\u00f3 Reyes.<\/p>\n<p>El viaje a Miami, sin embargo, requiere un importante esfuerzo econ\u00f3mico<em>. \u00abObviamente es un gasto costoso viajar, por lo que esperamos poder contar con el apoyo de la comunidad del Valle de Aconcagua\u00bb,<\/em> sostuvo la directora.<\/p>\n<p>Finalmente, Reyes envi\u00f3 un mensaje a las familias y a la comuna. <em>\u00abNosotros trabajamos para que nuestros jugadores puedan proyectarse a trav\u00e9s de un trabajo exigente. Invitamos a la comunidad a confiar en nuestro proyecto formativo y de proyecci\u00f3n, que est\u00e1 respaldado por nuestro jefe t\u00e9cnico, el experto en f\u00fatbol formativo <strong>Ariel Lara<\/strong>\u00bb<\/em>, concluy\u00f3 la directora.<\/p>\n<figure id=\"attachment_139368\" aria-describedby=\"caption-attachment-139368\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-139368\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-1.jpg\" alt=\"El equipo 2016 de la Escuela de F\u00fatbol Universidad de Chile San Felipe celebrando su campeonato nacional.\" width=\"699\" height=\"466\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-1.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-1-300x200.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-1-630x420.jpg 630w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-1-150x100.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-1-696x464.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-139368\" class=\"wp-caption-text\">El equipo 2016 de la Escuela de F\u00fatbol Universidad de Chile San Felipe celebrando su campeonato nacional.<\/figcaption><\/figure>\n<figure id=\"attachment_139367\" aria-describedby=\"caption-attachment-139367\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-139367\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-2.jpg\" alt=\"Algunos de los ni\u00f1os felices celebrando su hist\u00f3rica victoria.\" width=\"699\" height=\"466\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-2.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-2-300x200.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-2-630x420.jpg 630w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-2-150x100.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-2-696x464.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-139367\" class=\"wp-caption-text\">Algunos de los ni\u00f1os felices celebrando su hist\u00f3rica victoria.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ahora se encuentran disputando el torneo de Iniciaci\u00f3n ANFP y esperan con ansias el gran desaf\u00edo internacional: la Miami Cup 2026.- Un verdadero orgullo para San Felipe es lo que logr\u00f3 la categor\u00eda 2016 de la Escuela de F\u00fatbol Universidad de Chile San Felipe, que el pasado 15 y 16 de agosto se coron\u00f3 campeona [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":139367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-139366","post","type-post","status-publish","format-standard","has-post-thumbnail","category-comunidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Escuela U. de Chile San Felipe categor\u00eda 2016 se corona campeona nacional - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escuela U. de Chile San Felipe categor\u00eda 2016 se corona campeona nacional - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Ahora se encuentran disputando el torneo de Iniciaci\u00f3n ANFP y esperan con ansias el gran desaf\u00edo internacional: la Miami Cup 2026.- Un verdadero orgullo para San Felipe es lo que logr\u00f3 la categor\u00eda 2016 de la Escuela de F\u00fatbol Universidad de Chile San Felipe, que el pasado 15 y 16 de agosto se coron\u00f3 campeona [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-21T00:40:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"699\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Escuela U. de Chile San Felipe categor\u00eda 2016 se corona campeona nacional\",\"datePublished\":\"2025-08-21T00:40:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\\\/\"},\"wordCount\":525,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/escuela-U-sanfe-2.jpg\",\"articleSection\":[\"Comunidad\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\\\/\",\"name\":\"Escuela U. de Chile San Felipe categor\u00eda 2016 se corona campeona nacional - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/escuela-U-sanfe-2.jpg\",\"datePublished\":\"2025-08-21T00:40:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/escuela-U-sanfe-2.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/escuela-U-sanfe-2.jpg\",\"width\":699,\"height\":466,\"caption\":\"Algunos de los ni\u00f1os felices celebrando su hist\u00f3rica victoria.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escuela U. de Chile San Felipe categor\u00eda 2016 se corona campeona nacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escuela U. de Chile San Felipe categor\u00eda 2016 se corona campeona nacional - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/","og_locale":"es_ES","og_type":"article","og_title":"Escuela U. de Chile San Felipe categor\u00eda 2016 se corona campeona nacional - Diario El Trabajo","og_description":"Ahora se encuentran disputando el torneo de Iniciaci\u00f3n ANFP y esperan con ansias el gran desaf\u00edo internacional: la Miami Cup 2026.- Un verdadero orgullo para San Felipe es lo que logr\u00f3 la categor\u00eda 2016 de la Escuela de F\u00fatbol Universidad de Chile San Felipe, que el pasado 15 y 16 de agosto se coron\u00f3 campeona [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2025-08-21T00:40:07+00:00","og_image":[{"width":699,"height":466,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-2.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Escuela U. de Chile San Felipe categor\u00eda 2016 se corona campeona nacional","datePublished":"2025-08-21T00:40:07+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/"},"wordCount":525,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-2.jpg","articleSection":["Comunidad"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/","url":"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/","name":"Escuela U. de Chile San Felipe categor\u00eda 2016 se corona campeona nacional - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-2.jpg","datePublished":"2025-08-21T00:40:07+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-2.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/08\/escuela-U-sanfe-2.jpg","width":699,"height":466,"caption":"Algunos de los ni\u00f1os felices celebrando su hist\u00f3rica victoria."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/escuela-u-de-chile-san-felipe-categoria-2016-se-corona-campeona-nacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Escuela U. de Chile San Felipe categor\u00eda 2016 se corona campeona nacional"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/139366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=139366"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/139366\/revisions"}],"predecessor-version":[{"id":139369,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/139366\/revisions\/139369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/139367"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=139366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=139366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=139366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}