{"id":140072,"date":"2025-09-25T20:46:59","date_gmt":"2025-09-25T23:46:59","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=140072"},"modified":"2025-09-25T20:46:59","modified_gmt":"2025-09-25T23:46:59","slug":"la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/","title":{"rendered":"La urgencia de hablar de suicidio en Chile y c\u00f3mo podemos actuar"},"content":{"rendered":"<p>Hablar de suicidio sigue siendo dif\u00edcil. Pesa un silencio inc\u00f3modo, un estigma que obliga al sufrimiento a ocultarse, muchas veces hasta que es demasiado tarde. Pero mientras callamos, las cifras gritan: Chile tiene una de las tasas de suicidio m\u00e1s altas de Am\u00e9rica Latina, con 10,3 casos por cada 100.000 habitantes, seg\u00fan la Organizaci\u00f3n Panamericana de la Salud. En a\u00f1os recientes, incluso ha superado a la tasa de homicidios.<\/p>\n<p>Este no es solo un problema de salud mental individual. Es un fen\u00f3meno complejo, atravesado por factores estructurales: desigualdad, aislamiento, falta de redes, precariedad del sistema de salud mental y estigmas sociales. En este contexto, la prevenci\u00f3n no puede recaer solo en especialistas. Es una responsabilidad compartida.<\/p>\n<p><strong>Avances y desaf\u00edos<\/strong><\/p>\n<p>Desde el Estado se han impulsado iniciativas como la gu\u00eda pr\u00e1ctica de prevenci\u00f3n para estudiantes de educaci\u00f3n superior y la l\u00ednea gratuita *4141, disponible 24\/7. Sin embargo, persisten desaf\u00edos: falta de coordinaci\u00f3n entre niveles de atenci\u00f3n, equipos sobrecargados y personas que no piden ayuda por miedo o verg\u00fcenza.<\/p>\n<p><strong>Una respuesta <\/strong><strong>desde la academia<\/strong><\/p>\n<p>En este escenario, el rol de las universidades es crucial. No solo forman profesionales, tambi\u00e9n son espacios para promover pensamiento cr\u00edtico y transformaci\u00f3n social.<\/p>\n<p>En esa l\u00ednea, la Universidad de Aconcagua, a trav\u00e9s de su Facultad de Humanidades, Ciencias Jur\u00eddicas y Sociales y su Escuela de Psicolog\u00eda, ha organizado el seminario <strong>\u2018Prevenci\u00f3n del suicidio: herramientas de abordaje desde un enfoque integrado\u2019<\/strong>, que se realizar\u00e1 de manera presencial en la sede Machal\u00ed y tambi\u00e9n de forma virtual a trav\u00e9s de la plataforma TEAMS, permitiendo la participaci\u00f3n de todo p\u00fablico, desde cualquier punto del pa\u00eds y de forma gratuita.<\/p>\n<p>El evento est\u00e1 programado para el <strong>martes 30 de septiembre a las 19:00 horas<\/strong>, y contar\u00e1 con la participaci\u00f3n de los profesionales <strong>Alejandro P\u00e9rez Oportus<\/strong>, psic\u00f3logo y Delegado Presidencial de O\u2019Higgins, y <strong>Alejandro Gonz\u00e1lez Medina<\/strong>, psic\u00f3logo cl\u00ednico y especialista en salud mental organizacional. Los interesados solo deben registrase en: <u>https:\/\/forms.office.com\/r\/HmuPiqm8GR<\/u><\/p>\n<p>Este seminario busca capacitar a la comunidad en detecci\u00f3n temprana, intervenci\u00f3n segura y derivaci\u00f3n responsable, desde un enfoque \u00e9tico, cl\u00ednico y comunitario.<\/p>\n<p>El decano de la Facultad, abogado <strong>Enzo Botto<\/strong>, destaca: <em>\u00abComo Universidad, debemos abrir nuestras puertas al di\u00e1logo m\u00e1s urgente. Este seminario es una apuesta por instalar una<\/em> <em>conversaci\u00f3n informada, con respaldo acad\u00e9mico y humano. No basta con diagnosticar el sufrimiento: debemos formar a quienes puedan prevenirlo\u00bb.<\/em><\/p>\n<p>Por su parte, la directora de la Escuela de Psicolog\u00eda, psic\u00f3loga <strong>Denisse Gonz\u00e1lez<\/strong>, enfatiza<em>: \u00abLa psicolog\u00eda tiene una misi\u00f3n social que va m\u00e1s all\u00e1 del entorno terap\u00e9utico. Es urgente formar agentes de prevenci\u00f3n en escuelas, centros de salud y comunidades. Este seminario es un paso en esa direcci\u00f3n\u00bb.<\/em><\/p>\n<p><strong>\u00a0<\/strong><strong>Hablar puede <\/strong><strong>salvar vidas<\/strong><\/p>\n<p>Hablar de suicidio con responsabilidad, sin prejuicios ni morbo, es un acto de cuidado. Saber escuchar, contener y conectar a una persona en riesgo con ayuda especializada puede marcar la diferencia.<\/p>\n<p>Prevenir el suicidio es una tarea de todos. Este seminario es una oportunidad concreta para comenzar.<\/p>\n<figure id=\"attachment_140073\" aria-describedby=\"caption-attachment-140073\" style=\"width: 698px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-140073\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/09\/UAC.jpg\" alt=\"El Decano de la Facultad, abogado Enzo Botto Mu\u00f1oz; y la Directora de la Escuela de Psicolog\u00eda, psic\u00f3loga Denisse Gonz\u00e1lez.\" width=\"698\" height=\"412\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/09\/UAC.jpg 698w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/09\/UAC-300x177.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/09\/UAC-150x89.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/09\/UAC-696x411.jpg 696w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><figcaption id=\"caption-attachment-140073\" class=\"wp-caption-text\">El Decano de la Facultad, abogado Enzo Botto Mu\u00f1oz; y la Directora de la Escuela de Psicolog\u00eda, psic\u00f3loga Denisse Gonz\u00e1lez.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Hablar de suicidio sigue siendo dif\u00edcil. Pesa un silencio inc\u00f3modo, un estigma que obliga al sufrimiento a ocultarse, muchas veces hasta que es demasiado tarde. Pero mientras callamos, las cifras gritan: Chile tiene una de las tasas de suicidio m\u00e1s altas de Am\u00e9rica Latina, con 10,3 casos por cada 100.000 habitantes, seg\u00fan la Organizaci\u00f3n Panamericana [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":140073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-140072","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cronica-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La urgencia de hablar de suicidio en Chile y c\u00f3mo podemos actuar - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La urgencia de hablar de suicidio en Chile y c\u00f3mo podemos actuar - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Hablar de suicidio sigue siendo dif\u00edcil. Pesa un silencio inc\u00f3modo, un estigma que obliga al sufrimiento a ocultarse, muchas veces hasta que es demasiado tarde. Pero mientras callamos, las cifras gritan: Chile tiene una de las tasas de suicidio m\u00e1s altas de Am\u00e9rica Latina, con 10,3 casos por cada 100.000 habitantes, seg\u00fan la Organizaci\u00f3n Panamericana [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-25T23:46:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/09\/UAC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"698\" \/>\n\t<meta property=\"og:image:height\" content=\"412\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"La urgencia de hablar de suicidio en Chile y c\u00f3mo podemos actuar\",\"datePublished\":\"2025-09-25T23:46:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\\\/\"},\"wordCount\":586,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/UAC.jpg\",\"articleSection\":[\"Cr\u00f3nica\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\\\/\",\"name\":\"La urgencia de hablar de suicidio en Chile y c\u00f3mo podemos actuar - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/UAC.jpg\",\"datePublished\":\"2025-09-25T23:46:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/UAC.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/UAC.jpg\",\"width\":698,\"height\":412,\"caption\":\"El Decano de la Facultad, abogado Enzo Botto Mu\u00f1oz; y la Directora de la Escuela de Psicolog\u00eda, psic\u00f3loga Denisse Gonz\u00e1lez.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La urgencia de hablar de suicidio en Chile y c\u00f3mo podemos actuar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La urgencia de hablar de suicidio en Chile y c\u00f3mo podemos actuar - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/","og_locale":"es_ES","og_type":"article","og_title":"La urgencia de hablar de suicidio en Chile y c\u00f3mo podemos actuar - Diario El Trabajo","og_description":"Hablar de suicidio sigue siendo dif\u00edcil. Pesa un silencio inc\u00f3modo, un estigma que obliga al sufrimiento a ocultarse, muchas veces hasta que es demasiado tarde. Pero mientras callamos, las cifras gritan: Chile tiene una de las tasas de suicidio m\u00e1s altas de Am\u00e9rica Latina, con 10,3 casos por cada 100.000 habitantes, seg\u00fan la Organizaci\u00f3n Panamericana [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2025-09-25T23:46:59+00:00","og_image":[{"width":698,"height":412,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/09\/UAC.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"La urgencia de hablar de suicidio en Chile y c\u00f3mo podemos actuar","datePublished":"2025-09-25T23:46:59+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/"},"wordCount":586,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/09\/UAC.jpg","articleSection":["Cr\u00f3nica"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/","url":"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/","name":"La urgencia de hablar de suicidio en Chile y c\u00f3mo podemos actuar - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/09\/UAC.jpg","datePublished":"2025-09-25T23:46:59+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/09\/UAC.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/09\/UAC.jpg","width":698,"height":412,"caption":"El Decano de la Facultad, abogado Enzo Botto Mu\u00f1oz; y la Directora de la Escuela de Psicolog\u00eda, psic\u00f3loga Denisse Gonz\u00e1lez."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/la-urgencia-de-hablar-de-suicidio-en-chile-y-como-podemos-actuar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"La urgencia de hablar de suicidio en Chile y c\u00f3mo podemos actuar"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/140072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=140072"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/140072\/revisions"}],"predecessor-version":[{"id":140074,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/140072\/revisions\/140074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/140073"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=140072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=140072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=140072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}