{"id":140241,"date":"2025-10-02T20:33:57","date_gmt":"2025-10-02T23:33:57","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=140241"},"modified":"2025-10-02T20:33:57","modified_gmt":"2025-10-02T23:33:57","slug":"san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/","title":{"rendered":"San Felipe ser\u00e1 sede de la tercera fecha de la Liga Binacional Aconcagua de Patinaje"},"content":{"rendered":"<ul>\n<li><strong>El Club Prosperidad ser\u00e1 anfitri\u00f3n de la jornada, que se extender\u00e1 durante todo el d\u00eda.-<\/strong><\/li>\n<\/ul>\n<p>Nuestra comuna vivir\u00e1 una fiesta deportiva el pr\u00f3ximo s\u00e1bado 11 de octubre con la realizaci\u00f3n de la tercera fecha de la Liga Binacional Aconcagua de Patinaje, un evento que convoca a m\u00e1s de 200 competidores provenientes de diferentes ciudades de Chile y Argentina. La jornada tendr\u00e1 lugar en calle Mar\u00eda Eufrasia con Hermanos Carrera Oriente, y se desarrollar\u00e1 desde las 9:00 de la ma\u00f1ana hasta las 18:00 horas aproximadamente.<\/p>\n<p>La liga, que contempla un total de cuatro fechas, comenz\u00f3 el pasado 12 de abril en Los Andes, bajo la organizaci\u00f3n de la Academia Patinaje Aconcagua, y continu\u00f3 el 7 de junio en Valpara\u00edso gracias al trabajo del Club NAP. Ahora, ser\u00e1 el turno de San Felipe con la organizaci\u00f3n del Club Prosperidad, mientras que la gran final se disputar\u00e1 el 6 de diciembre en Argentina.<\/p>\n<p>Los organizadores destacan que en cada encuentro se han reunido alrededor de 210 participantes, lo que da cuenta del crecimiento que ha tenido esta disciplina en la zona. La entrenadora del Club Prosperidad, <strong>Vania Ahumada<\/strong>, explic\u00f3 que este proceso ha sido muy enriquecedor para los ni\u00f1os y ni\u00f1as que reci\u00e9n se inician en el patinaje competitivo.<em> \u00abLa forma de trabajo con los alumnos ha sido un proceso muy motivador, ellos comenzaron desde cero en sus patines y ya est\u00e1n integr\u00e1ndose a competencias en las cuales van adquiriendo experiencia para avanzar a otras ligas\u00bb,<\/em> coment\u00f3.<\/p>\n<p>En las dos primeras fechas, los deportistas locales lograron excelentes resultados. Entre ellos, destacan los podios de <strong>Rafaella Salas<\/strong> (3\u00ba lugar), <strong>Mil\u00e1n Colarte<\/strong> (1\u00ba lugar), <strong>Vicente Carvallo<\/strong> (2\u00ba lugar), <strong>L\u00eda Basualdo<\/strong> (2\u00ba lugar), <strong>Mat\u00edas Lazcano<\/strong> (2\u00ba lugar) e <strong>Isidora Arancibia<\/strong> (3\u00ba lugar). Estos logros han sido especialmente valorados por los apoderados, considerando que el club apenas lleva un a\u00f1o y medio de funcionamiento.<\/p>\n<p>El crecimiento del Club Prosperidad ha estado marcado por la autogesti\u00f3n y el esfuerzo colectivo. <em>\u00abAl llevar un a\u00f1o y medio como club, los apoderados est\u00e1n muy contentos con sus avances. Debo mencionar la autogesti\u00f3n y el apoyo completo del club, las actividades como plato \u00fanico y rifas que se gestionaron para ir a Valpara\u00edso a participar, principalmente el apoyo de apoderados, familiares y colegios en algunos casos de los alumnos\u00bb,<\/em> se\u00f1al\u00f3 Ahumada.<\/p>\n<p>El pr\u00f3ximo s\u00e1bado la cita en San Felipe no solo ser\u00e1 deportiva, sino tambi\u00e9n una instancia de uni\u00f3n comunitaria. El club dispondr\u00e1 de <em>stands<\/em> de venta de alimentos y productos para reunir fondos destinados a la participaci\u00f3n en la fecha final de la liga en Argentina.<em> \u00abLo cual nos favorece como club, porque al ser el evento todo el d\u00eda, quienes quieran apoyar pueden ir en cualquier horario. Tendremos cosas a la venta para reunir fondos para nuestra pr\u00f3xima participaci\u00f3n en Argentina, por lo cual es importante que vayan a apoyarnos como club\u00bb,<\/em> agreg\u00f3 la dirigente.<\/p>\n<p>No obstante, el crecimiento de la disciplina enfrenta tambi\u00e9n desaf\u00edos. Uno de los principales, es la falta de un recinto adecuado para los entrenamientos.<em> \u00abNuestro gran dilema es la cancha de entrenamiento, ya que estamos en una cancha en Poblaci\u00f3n La Escuadra, la cual no cumple con dimensiones para la actividad. Motivo por el cual tambi\u00e9n se suspendi\u00f3 la primera fecha que era el 30 de agosto, la cual se reprogram\u00f3 al 11 de octubre por no contar con un espacio techado para recibir a los 210 deportistas m\u00e1s sus entrenadores y apoderados\u00bb,<\/em> explic\u00f3 Ahumada.<\/p>\n<p>Pese a las dificultades, los ni\u00f1os y j\u00f3venes se han mostrado comprometidos y disciplinados, lo que entusiasma a los entrenadores y familias. El club, adem\u00e1s, ha ido sumando nuevos alumnos que ven en el patinaje una alternativa deportiva distinta y llena de desaf\u00edos.<\/p>\n<p>La Liga Binacional Aconcagua es organizada en conjunto por Pat\u00edn Aconcagua (Los Andes), Club NAP (Valpara\u00edso), Club Prosperidad (San Felipe) y Rollers Luj\u00e1n (Argentina). Con su car\u00e1cter internacional, se ha transformado en una instancia que no solo fomenta el deporte, sino que tambi\u00e9n fortalece lazos culturales y de amistad entre los j\u00f3venes de ambos pa\u00edses.<\/p>\n<figure id=\"attachment_140242\" aria-describedby=\"caption-attachment-140242\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-140242\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/10\/patinaje.jpg\" alt=\"Integrantes del club de patinaje \u2018Prosperidad\u2019.\" width=\"699\" height=\"416\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/10\/patinaje.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/10\/patinaje-300x179.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/10\/patinaje-150x89.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/10\/patinaje-696x414.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-140242\" class=\"wp-caption-text\">Integrantes del club de patinaje \u2018Prosperidad\u2019.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Club Prosperidad ser\u00e1 anfitri\u00f3n de la jornada, que se extender\u00e1 durante todo el d\u00eda.- Nuestra comuna vivir\u00e1 una fiesta deportiva el pr\u00f3ximo s\u00e1bado 11 de octubre con la realizaci\u00f3n de la tercera fecha de la Liga Binacional Aconcagua de Patinaje, un evento que convoca a m\u00e1s de 200 competidores provenientes de diferentes ciudades de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":140242,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-140241","post","type-post","status-publish","format-standard","has-post-thumbnail","category-comunidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Felipe ser\u00e1 sede de la tercera fecha de la Liga Binacional Aconcagua de Patinaje - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Felipe ser\u00e1 sede de la tercera fecha de la Liga Binacional Aconcagua de Patinaje - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"El Club Prosperidad ser\u00e1 anfitri\u00f3n de la jornada, que se extender\u00e1 durante todo el d\u00eda.- Nuestra comuna vivir\u00e1 una fiesta deportiva el pr\u00f3ximo s\u00e1bado 11 de octubre con la realizaci\u00f3n de la tercera fecha de la Liga Binacional Aconcagua de Patinaje, un evento que convoca a m\u00e1s de 200 competidores provenientes de diferentes ciudades de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-02T23:33:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/10\/patinaje.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"699\" \/>\n\t<meta property=\"og:image:height\" content=\"416\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"San Felipe ser\u00e1 sede de la tercera fecha de la Liga Binacional Aconcagua de Patinaje\",\"datePublished\":\"2025-10-02T23:33:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\\\/\"},\"wordCount\":731,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/patinaje.jpg\",\"articleSection\":[\"Comunidad\"],\"inLanguage\":\"es-CL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\\\/\",\"name\":\"San Felipe ser\u00e1 sede de la tercera fecha de la Liga Binacional Aconcagua de Patinaje - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/patinaje.jpg\",\"datePublished\":\"2025-10-02T23:33:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/patinaje.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/patinaje.jpg\",\"width\":699,\"height\":416,\"caption\":\"Integrantes del club de patinaje \u2018Prosperidad\u2019.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Felipe ser\u00e1 sede de la tercera fecha de la Liga Binacional Aconcagua de Patinaje\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Felipe ser\u00e1 sede de la tercera fecha de la Liga Binacional Aconcagua de Patinaje - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/","og_locale":"es_ES","og_type":"article","og_title":"San Felipe ser\u00e1 sede de la tercera fecha de la Liga Binacional Aconcagua de Patinaje - Diario El Trabajo","og_description":"El Club Prosperidad ser\u00e1 anfitri\u00f3n de la jornada, que se extender\u00e1 durante todo el d\u00eda.- Nuestra comuna vivir\u00e1 una fiesta deportiva el pr\u00f3ximo s\u00e1bado 11 de octubre con la realizaci\u00f3n de la tercera fecha de la Liga Binacional Aconcagua de Patinaje, un evento que convoca a m\u00e1s de 200 competidores provenientes de diferentes ciudades de [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2025-10-02T23:33:57+00:00","og_image":[{"width":699,"height":416,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/10\/patinaje.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"San Felipe ser\u00e1 sede de la tercera fecha de la Liga Binacional Aconcagua de Patinaje","datePublished":"2025-10-02T23:33:57+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/"},"wordCount":731,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/10\/patinaje.jpg","articleSection":["Comunidad"],"inLanguage":"es-CL"},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/","url":"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/","name":"San Felipe ser\u00e1 sede de la tercera fecha de la Liga Binacional Aconcagua de Patinaje - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/10\/patinaje.jpg","datePublished":"2025-10-02T23:33:57+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/10\/patinaje.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2025\/10\/patinaje.jpg","width":699,"height":416,"caption":"Integrantes del club de patinaje \u2018Prosperidad\u2019."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/san-felipe-sera-sede-de-la-tercera-fecha-de-la-liga-binacional-aconcagua-de-patinaje\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"San Felipe ser\u00e1 sede de la tercera fecha de la Liga Binacional Aconcagua de Patinaje"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/140241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=140241"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/140241\/revisions"}],"predecessor-version":[{"id":140243,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/140241\/revisions\/140243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/140242"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=140241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=140241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=140241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}