{"id":143733,"date":"2026-03-30T20:21:25","date_gmt":"2026-03-30T23:21:25","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=143733"},"modified":"2026-03-30T20:21:25","modified_gmt":"2026-03-30T23:21:25","slug":"alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/","title":{"rendered":"Alcaldes de la provincia y parlamentarios piden congelar tarifas del transporte por alza de combustibles"},"content":{"rendered":"<ul>\n<li><strong>Autoridades vaticinan un escenario econ\u00f3mico complejo para el invierno.\u2013<\/strong><\/li>\n<\/ul>\n<p>Con los mismos dramas econ\u00f3micos y sociales que trajo consigo la pandemia del Covid-19, as\u00ed ser\u00edan los inconvenientes que traer\u00eda el alza del precio de los combustibles seg\u00fan autoridades comunales de la provincia y parlamentarios de la zona.<\/p>\n<p>Esto, tras una reuni\u00f3n efectuada en el Teatro Municipal de San Felipe, en la que se abord\u00f3 esta tem\u00e1tica y se llegaron a propuestas que buscar\u00e1n entregar a las autoridades de Gobierno. En el encuentro, participaron los alcaldes y alcaldesa de San Felipe, Catemu y Putaendo, adem\u00e1s del senador <strong>Diego Ib\u00e1\u00f1ez<\/strong>, y el diputado <strong>Nelson Venegas<\/strong>.<\/p>\n<p>Al respecto, la alcaldesa de San Felipe, <strong>Carmen Castillo<\/strong>, se\u00f1al\u00f3 que <em>\u00abpara nosotros esta reuni\u00f3n es muy importante, porque estamos manifestando nuestra preocupaci\u00f3n por esta alza de combustibles que est\u00e1 provocando serio impacto en la calidad de vida de nuestros habitantes, especialmente con la parte social. Estamos muy preocupados, porque vemos que las regiones no est\u00e1n recibiendo apoyo en este \u00e1mbito y necesitamos que existan apoyos concretos\u00bb<\/em>, indic\u00f3.<\/p>\n<p>En este contexto, la edil agreg\u00f3 que <em>\u00abestamos pensando en subsidios, en cualquier otra alternativa, porque vemos que existen fondos que est\u00e1n siendo retenidos y que nos preocupan enormemente; en alg\u00fan momento se est\u00e1 planteando que el royalty <\/em>(minero) <em>est\u00e1 retenido\u00bb<\/em>.<\/p>\n<p>Por su parte, el alcalde de Putaendo, <strong>Mauricio Quiroz<\/strong> <strong>Chamorro<\/strong>, coment\u00f3 que <em>\u00aben primer lugar, no podemos ser tratados como lo est\u00e1 haciendo el Gobierno en este momento. A prop\u00f3sito de la subida important\u00edsima de los combustibles, ha determinado un sinn\u00famero de acciones para beneficiar a algunos chilenos, y eso nos parece lamentable, una discriminaci\u00f3n odiosa que no es aceptable\u00bb<\/em>, expres\u00f3.<\/p>\n<p>En este punto, el edil abog\u00f3 por mayores medidas concretas en beneficio de la comunidad. <em>\u00abRequerimos m\u00e1s certezas, m\u00e1s celeridad, y un paquete de medidas que beneficie a nuestras comunidades rurales que no est\u00e1n siendo consideradas en este momento en las medidas que se han aprobado en el Parlamento como en el Ejecutivo\u00bb<\/em>.<\/p>\n<p>Es as\u00ed, que Quiroz estableci\u00f3 que <em>\u00abcreemos que es indispensable avanzar en tener las cosas mucho m\u00e1s claras, si esta es una crisis que se va a prolongar por los pr\u00f3ximos seis meses o quiz\u00e1s mucho m\u00e1s tiempo, requerimos un Estado mucho m\u00e1s diligente, mucho m\u00e1s dispuesto a entregarle recursos adicionales a todas y cada una de las familias de nuestro pa\u00eds, sin discriminaci\u00f3n alguna\u00bb<\/em>, a\u00f1adi\u00f3.<\/p>\n<p>En este contexto, el alcalde de Putaendo asegur\u00f3 que <em>\u00absi hay subsidios y congelamiento de tarifas en la Regi\u00f3n Metropolitana, exigimos que tambi\u00e9n lo haya en el resto del pa\u00eds, y exigimos que seamos tratados de la misma forma de quienes viven en la Regi\u00f3n Metropolitana\u00bb<\/em>.<\/p>\n<p>Asimismo, el alcalde de Catemu, <strong>Rodrigo D\u00edaz<\/strong>, coment\u00f3 que <em>\u00abcuando el Gobierno anuncia, y el Parlamento luego aprueba una medida donde hablamos de la Ley Espejo, que se va a invertir lo mismo en regiones que es lo que ya se invierte en Santiago por el \u2018Transantiago\u2019, para nosotros eso no es real, nosotros no tenemos transporte subsidiado en la provincia. Lo que enfrentamos son alzas brutales que van entre el 30 y el 50% del transporte rural, del transporte interurbano e incluso de transporte para que nuestra gente llegue a Santiago\u00bb<\/em>, enfatiz\u00f3.<\/p>\n<p>En este punto, el edil sostuvo que <em>\u00abalzas del 50% son absolutamente insostenibles para cualquier econom\u00eda local. Cuando vamos a plantear que hay posibles ayudas y se dice que est\u00e1 la Ley Espejo, eso no es real, para la provincia no existe. Si queremos darle un aporte a la provincia, empecemos a hablar de un bono, empecemos a liberar los bonos tal como se liberaron durante la pandemia, porque no podemos pensar que medidas al mediano o largo plazo van a tener alg\u00fan efecto\u00bb<\/em>, estableci\u00f3 el alcalde.<\/p>\n<p>En este sentido, D\u00edaz indic\u00f3 que con este escenario, se vaticina un complejo futuro, sobre todo para los meses de invierno. <em>\u00abNo quiero estar en ese mes de julio o agosto, con un invierno fr\u00edo, lluvioso, con una inflaci\u00f3n de cuatro puntos, con nuestra gente pasando hambre. Hacia all\u00e1 vamos caminando si de no liberamos los apoyos hoy\u00bb<\/em>.<\/p>\n<p>Asimismo, Rodrigo D\u00edaz fue cr\u00edtico al asegurar que existe un retraso en la entrega de los recursos por la ley del Royalty Minero a las comunas beneficiadas, dineros, que seg\u00fan indic\u00f3, podr\u00eda ayudar a palear esta alza en el precio de los combustibles.<\/p>\n<p>\u00ab<em>Y por \u00faltimo, el royalty el a\u00f1o pasado a estas alturas ya estaba ingresado en las arcas del municipio, hoy, entendemos que no hay fecha disponible a\u00fan para un beneficio que realmente nos podr\u00eda ayudar para tener herramientas y satisfacer algunos de los problemas que va a empezar a presentar nuestra gente. Lamentablemente, no tenemos noticias, estamos pr\u00e1cticamente en abril, cuando el royalty ingresaba en febrero; hoy en abril, y no hay noticia del royalty\u00bb<\/em>, sostuvo.<\/p>\n<p>Por su parte, y a nivel parlamentario, el senador <strong>Diego Ib\u00e1\u00f1ez<\/strong>, coment\u00f3 que su presencia se da en el \u00e1mbito de <em>\u00abresponder al llamado de los alcaldes, creo que hoy el Gobierno est\u00e1 tomando malas medidas, hab\u00eda otras alternativas y no subir la bencina, el di\u00e9sel de golpe, porque todo lo que expresan es consecuencia de una mala decisi\u00f3n pol\u00edtica frente a la cual hab\u00eda otras alternativas\u00bb<\/em>.<\/p>\n<p>En este contexto, Ib\u00e1\u00f1ez abog\u00f3 incluso en que se analice la posibilidad de poder entregar recursos directos a las familias, tal como se efectu\u00f3 en la \u00e9poca de pandemia. <em>\u00abAs\u00ed como se congel\u00f3 la tarifa en Santiago, tambi\u00e9n se congele la tarifa en regiones y se encuentren los mecanismos para subsidiar el transporte p\u00fablico. Que existan ayudas directas a la poblaci\u00f3n, que se eval\u00fae la posibilidad de un IFE<\/em> (Ingreso Familiar de Emergencia) <em>tal cual ocurri\u00f3 en pandemia, que lleguen los recursos para los que m\u00e1s lo necesitan y escuchar a los alcaldes de regiones\u00bb<\/em>, agreg\u00f3.<\/p>\n<p>Finalmente, el diputado <strong>Nelson Venegas<\/strong>, se\u00f1al\u00f3 que <em>\u00ablas autoridades cuando son serias se anticipan a las cosas y adem\u00e1s son emp\u00e1ticas, aqu\u00ed estamos hablando que en el invierno va a haber verdaderos dramas y va a haber hambre, de eso hablamos. Si no somos capaces de escuchar a los que m\u00e1s saben en los terrenos, los alcaldes y alcaldesas, es que no estamos entendiendo nada\u00bb<\/em>.<\/p>\n<p>En as\u00ed, que al igual como expres\u00f3 el senador Ib\u00e1\u00f1ez, Venegas sostuvo que esperan reunirse con las autoridades de Gobierno para plantear estos requerimientos y propuestas.<\/p>\n<p>\u00ab<em>Vamos a ir y llevar propuestas concretas para plantearlas a la ministra de Desarrollo Social, al ministro de Transportes y a cualquier otro ministro, porque insistimos, la situaci\u00f3n ac\u00e1 en el invierno va a ser dram\u00e1tica, va a volver el hambre como existi\u00f3 en la \u00e9poca de la pandemia si es que no somos capaces de anticiparnos\u00bb<\/em>, indic\u00f3.<\/p>\n<p>Por \u00faltimo, el diputado concluy\u00f3 que <em>\u00absolicitaremos en concreto subsidios para los sectores m\u00e1s pobres, tambi\u00e9n respecto del transporte rural. Es inaceptable que siempre se siga postergando a las provincias, a las regiones, ac\u00e1 se est\u00e1 gobernando por decreto, sin entender lo que ocurre en las necesidades de la gente\u00bb<\/em>.<\/p>\n<figure id=\"attachment_143734\" aria-describedby=\"caption-attachment-143734\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-143734\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/03\/alcaldes-de-la-provincia-y-parlamentarios.jpg\" alt=\"Autoridades piden congelar tarifas del transporte por el alza en el precio de los combustibles. \" width=\"699\" height=\"451\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/03\/alcaldes-de-la-provincia-y-parlamentarios.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/03\/alcaldes-de-la-provincia-y-parlamentarios-300x194.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/03\/alcaldes-de-la-provincia-y-parlamentarios-651x420.jpg 651w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/03\/alcaldes-de-la-provincia-y-parlamentarios-150x97.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/03\/alcaldes-de-la-provincia-y-parlamentarios-696x449.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-143734\" class=\"wp-caption-text\">Autoridades piden congelar tarifas del transporte por el alza en el precio de los combustibles.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades vaticinan un escenario econ\u00f3mico complejo para el invierno.\u2013 Con los mismos dramas econ\u00f3micos y sociales que trajo consigo la pandemia del Covid-19, as\u00ed ser\u00edan los inconvenientes que traer\u00eda el alza del precio de los combustibles seg\u00fan autoridades comunales de la provincia y parlamentarios de la zona. Esto, tras una reuni\u00f3n efectuada en el Teatro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":143734,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-143733","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cronica-2"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alcaldes de la provincia y parlamentarios piden congelar tarifas del transporte por alza de combustibles - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alcaldes de la provincia y parlamentarios piden congelar tarifas del transporte por alza de combustibles - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Autoridades vaticinan un escenario econ\u00f3mico complejo para el invierno.\u2013 Con los mismos dramas econ\u00f3micos y sociales que trajo consigo la pandemia del Covid-19, as\u00ed ser\u00edan los inconvenientes que traer\u00eda el alza del precio de los combustibles seg\u00fan autoridades comunales de la provincia y parlamentarios de la zona. Esto, tras una reuni\u00f3n efectuada en el Teatro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-30T23:21:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/03\/alcaldes-de-la-provincia-y-parlamentarios.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"699\" \/>\n\t<meta property=\"og:image:height\" content=\"451\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Alcaldes de la provincia y parlamentarios piden congelar tarifas del transporte por alza de combustibles\",\"datePublished\":\"2026-03-30T23:21:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\\\/\"},\"wordCount\":1262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/alcaldes-de-la-provincia-y-parlamentarios.jpg\",\"articleSection\":[\"Cr\u00f3nica\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\\\/\",\"name\":\"Alcaldes de la provincia y parlamentarios piden congelar tarifas del transporte por alza de combustibles - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/alcaldes-de-la-provincia-y-parlamentarios.jpg\",\"datePublished\":\"2026-03-30T23:21:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/alcaldes-de-la-provincia-y-parlamentarios.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/alcaldes-de-la-provincia-y-parlamentarios.jpg\",\"width\":699,\"height\":451,\"caption\":\"Autoridades piden congelar tarifas del transporte por el alza en el precio de los combustibles.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alcaldes de la provincia y parlamentarios piden congelar tarifas del transporte por alza de combustibles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alcaldes de la provincia y parlamentarios piden congelar tarifas del transporte por alza de combustibles - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/","og_locale":"es_ES","og_type":"article","og_title":"Alcaldes de la provincia y parlamentarios piden congelar tarifas del transporte por alza de combustibles - Diario El Trabajo","og_description":"Autoridades vaticinan un escenario econ\u00f3mico complejo para el invierno.\u2013 Con los mismos dramas econ\u00f3micos y sociales que trajo consigo la pandemia del Covid-19, as\u00ed ser\u00edan los inconvenientes que traer\u00eda el alza del precio de los combustibles seg\u00fan autoridades comunales de la provincia y parlamentarios de la zona. Esto, tras una reuni\u00f3n efectuada en el Teatro [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2026-03-30T23:21:25+00:00","og_image":[{"width":699,"height":451,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/03\/alcaldes-de-la-provincia-y-parlamentarios.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Alcaldes de la provincia y parlamentarios piden congelar tarifas del transporte por alza de combustibles","datePublished":"2026-03-30T23:21:25+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/"},"wordCount":1262,"commentCount":0,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/03\/alcaldes-de-la-provincia-y-parlamentarios.jpg","articleSection":["Cr\u00f3nica"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/","url":"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/","name":"Alcaldes de la provincia y parlamentarios piden congelar tarifas del transporte por alza de combustibles - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/03\/alcaldes-de-la-provincia-y-parlamentarios.jpg","datePublished":"2026-03-30T23:21:25+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/03\/alcaldes-de-la-provincia-y-parlamentarios.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/03\/alcaldes-de-la-provincia-y-parlamentarios.jpg","width":699,"height":451,"caption":"Autoridades piden congelar tarifas del transporte por el alza en el precio de los combustibles."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/alcaldes-de-la-provincia-y-parlamentarios-piden-congelar-tarifas-del-transporte-por-alza-de-combustibles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Alcaldes de la provincia y parlamentarios piden congelar tarifas del transporte por alza de combustibles"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/143733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=143733"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/143733\/revisions"}],"predecessor-version":[{"id":143735,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/143733\/revisions\/143735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/143734"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=143733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=143733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=143733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}