{"id":144474,"date":"2026-05-06T21:58:45","date_gmt":"2026-05-07T00:58:45","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=144474"},"modified":"2026-05-06T21:58:45","modified_gmt":"2026-05-07T00:58:45","slug":"vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/","title":{"rendered":"Vecina denuncia reiteradas obstrucciones vehiculares en salida de su vivienda: Qued\u00f3 bloqueada y debi\u00f3 viajar en bus a control m\u00e9dico"},"content":{"rendered":"<ul>\n<li><strong>El veh\u00edculo permaneci\u00f3 m\u00e1s de ocho horas frente a su domicilio, pese a la intervenci\u00f3n de autoridades. Desde el municipio detallaron protocolos y anunciaron implementaci\u00f3n de sistema de retiro con gr\u00faa.-<\/strong><\/li>\n<\/ul>\n<p>Una compleja situaci\u00f3n vivi\u00f3 la vecina del centro de San Felipe, <strong>Carolina \u00c1lvarez<\/strong>, luego que un veh\u00edculo estacionado frente a su domicilio le impidiera salir con su autom\u00f3vil este lunes 4 de mayo, afectando directamente su traslado a un control m\u00e9dico en Santiago.<\/p>\n<p>El hecho ocurri\u00f3 en calle Santo Domingo, entre Navarro y Traslavi\u00f1a, donde, seg\u00fan relat\u00f3 la afectada, este tipo de situaciones no es aislado, sino m\u00e1s bien recurrente. <em>\u00abEsta situaci\u00f3n me ha sido bastante reiterativa en el sector donde yo vivo\u2026 todos los d\u00edas me obstaculizan la salida de veh\u00edculo\u00bb<\/em>, se\u00f1al\u00f3.<\/p>\n<p>Sin embargo, lo ocurrido esa jornada tuvo consecuencias mayores. <em>\u00abAyer (lunes) fue grave porque yo ten\u00eda un control en Santiago con neur\u00f3logo\u2026 Despu\u00e9s tuve que partir en bus a Santiago, porque no se pudo sacar el auto\u00bb<\/em>, explic\u00f3.<\/p>\n<p>El veh\u00edculo en cuesti\u00f3n se estacion\u00f3 poco antes de las 12:00 horas y permaneci\u00f3 en el lugar hasta pasadas las 20:00 horas, bloqueando completamente la salida de su vivienda. Durante ese tiempo, la vecina intent\u00f3 resolver la situaci\u00f3n contactando a las autoridades. <em>\u00abEstuve m\u00e1s de una hora intentando sacar mi auto, llamando, esperando alguna soluci\u00f3n, pero no pas\u00f3 nada\u00bb<\/em>, indic\u00f3.<\/p>\n<p>Pese a la llegada de personal municipal y de Carabineros, quienes cursaron la infracci\u00f3n correspondiente, el autom\u00f3vil no fue retirado del lugar. <em>\u00abVinieron, le sacaron un parte a un veh\u00edculo que ya lleva diez partes antiguos y sigue circulando, y el municipio y Carabineros no fueron capaces de dar una soluci\u00f3n\u00bb<\/em>, manifest\u00f3.<\/p>\n<p>Ante la urgencia de su compromiso m\u00e9dico, Carolina \u00c1lvarez se vio obligada a cambiar sus planes. <em>\u00abTuve que salir r\u00e1pidamente al terminal, tomar un colectivo\u2026 no deber\u00eda haber ido sola, pero dada las circunstancias tuve que partir sola a Santiago\u00bb<\/em>, relat\u00f3, agregando que padece problemas de memoria y que habitualmente viaja acompa\u00f1ada para evitar este tipo de situaciones.<\/p>\n<p>El contratiempo le signific\u00f3 llegar con retraso a su consulta. <em>\u00abLlegu\u00e9 5 minutos tarde en la consulta, gracias a Dios me lograron atender\u00bb<\/em>, coment\u00f3. No obstante, indic\u00f3 que el proceso fue altamente estresante.<\/p>\n<p>La vecina tambi\u00e9n expres\u00f3 su preocupaci\u00f3n por la falta de medidas m\u00e1s concretas para enfrentar este tipo de infracciones. <em>\u00abMe parece il\u00f3gico que el municipio, teniendo los recursos econ\u00f3micos, no invierta en tener una gr\u00faa para poder sacar este mal h\u00e1bito\u00bb<\/em>, sostuvo.<\/p>\n<p>En esa misma l\u00ednea, hizo un llamado a reforzar la fiscalizaci\u00f3n en el sector c\u00e9ntrico. <em>\u00abNecesito que el municipio se comprometa\u2026 a aumentar el tema de las fiscalizaciones ac\u00e1 en el casco hist\u00f3rico y no esperar que uno tenga que pasar todas estas molestias\u00bb<\/em>, indic\u00f3.<\/p>\n<p>Asimismo, advirti\u00f3 que la problem\u00e1tica no solo afecta a residentes, sino tambi\u00e9n a otros espacios sensibles como establecimientos educacionales, explicando que muchos conductores se estacionan en lugares no habilitados, incluso en zonas destinadas al descenso de estudiantes. Esta situaci\u00f3n obliga a apoderados y ni\u00f1os a bajar en la v\u00eda p\u00fablica o a mitad de cuadra, aumentando el riesgo de accidentes. <em>\u00abPodr\u00edan atropellar a cualquier chiquitito\u00bb<\/em>, advirti\u00f3, recalcando la necesidad de mayor fiscalizaci\u00f3n y educaci\u00f3n vial en estos sectores.<\/p>\n<p>Desde el municipio, el director de la Direcci\u00f3n de Seguridad Ciudadana, <strong>Felipe Olivares<\/strong>, explic\u00f3 los procedimientos que se aplican en estos casos. <em>\u00abPor lo general se fiscaliza cuando hay una alerta ciudadana\u2026 toda vez que en primera instancia no se tiene certeza si es que es un veh\u00edculo de la misma propiedad o un veh\u00edculo ajeno\u00bb<\/em>, se\u00f1al\u00f3.<\/p>\n<p>Respecto a las acciones concretas, explic\u00f3 que <em>\u00ablo primero que aplica es la infracci\u00f3n\u00bb<\/em>, agregando que en algunos casos se logra ubicar al conductor y resolver la situaci\u00f3n en el momento.<\/p>\n<p>En relaci\u00f3n a la disponibilidad de gr\u00faas, Olivares precis\u00f3 que recientemente se avanz\u00f3 en una soluci\u00f3n concreta para enfrentar este tipo de situaciones. <em>\u00abHace un par de semanas atr\u00e1s terminamos los tr\u00e1mites\u2026 con un aparcadero\u2026 en consecuencia, desde su operaci\u00f3n, los veh\u00edculos que est\u00e9n en falta grave\u2026 van a ser retirados de la v\u00eda p\u00fablica\u00bb<\/em>, afirm\u00f3.<\/p>\n<p>En ese sentido, detall\u00f3 que este convenio permitir\u00e1 actuar en casos como obstrucci\u00f3n de accesos vehiculares, estacionamientos en lugares prohibidos o veh\u00edculos sin documentaci\u00f3n al d\u00eda, situaciones que hasta ahora no siempre pod\u00edan resolverse de forma inmediata en terreno.<\/p>\n<p>Este sistema, adem\u00e1s, implicar\u00e1 costos asociados para el infractor. <em>\u00abEl infractor, adem\u00e1s de costear la multa, debe costear los costos del traslado de la gr\u00faa\u2026 e ir a recuperar su veh\u00edculo\u00bb<\/em>, explic\u00f3. De esta forma, el retiro no solo busca despejar la v\u00eda, sino tambi\u00e9n generar un efecto disuasivo en los conductores que incurren en este tipo de faltas, trasladando el veh\u00edculo hasta el aparcadero ubicado fuera de la comuna, donde deber\u00e1 ser retirado posteriormente por su propietario.<\/p>\n<p>En cuanto a la fiscalizaci\u00f3n, asegur\u00f3 que esta es permanente. <em>\u00abLas inspecciones son diarias\u2026 en promedio son 100 a 150 infracciones a la ley de tr\u00e1nsito\u00bb<\/em>, indic\u00f3, a\u00f1adiendo que estas se realizan tanto en el centro como en sectores aleda\u00f1os.<\/p>\n<p>Finalmente, indic\u00f3 que los vecinos pueden dar aviso a trav\u00e9s de Carabineros o directamente al municipio, reiterando adem\u00e1s los canales de contacto disponibles para la comunidad. <em>\u00abA nivel <strong>133<\/strong> o a la central municipal\u2026 el n\u00famero es el <strong>34 2 509 000<\/strong>\u00bb<\/em>, concluy\u00f3.<\/p>\n<figure id=\"attachment_144479\" aria-describedby=\"caption-attachment-144479\" style=\"width: 698px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-144479\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-4.jpg\" alt=\"Personal municipal y Carabineros cursaron una infracci\u00f3n al veh\u00edculo mal estacionado, que manten\u00eda bloqueada la salida del domicilio.\" width=\"698\" height=\"622\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-4.jpg 698w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-4-300x267.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-4-471x420.jpg 471w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-4-150x134.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-4-696x620.jpg 696w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><figcaption id=\"caption-attachment-144479\" class=\"wp-caption-text\">Personal municipal y Carabineros cursaron una infracci\u00f3n al veh\u00edculo mal estacionado, que manten\u00eda bloqueada la salida del domicilio.<\/figcaption><\/figure>\n<figure id=\"attachment_144476\" aria-describedby=\"caption-attachment-144476\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-144476\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-1.jpg\" alt=\"El veh\u00edculo permaneci\u00f3 por m\u00e1s de ocho horas bloqueando la salida de la vivienda de la vecina en pleno centro de San Felipe.\" width=\"700\" height=\"700\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-1.jpg 700w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-1-300x300.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-1-150x150.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-1-420x420.jpg 420w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-1-696x696.jpg 696w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-144476\" class=\"wp-caption-text\">El veh\u00edculo permaneci\u00f3 por m\u00e1s de ocho horas bloqueando la salida de la vivienda de la vecina en pleno centro de San Felipe.<\/figcaption><\/figure>\n<figure id=\"attachment_144477\" aria-describedby=\"caption-attachment-144477\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-144477\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-2.jpg\" alt=\"Ante la imposibilidad de salir en su veh\u00edculo, Carolina \u00c1lvarez debi\u00f3 trasladarse en bus a Santiago para no perder su control m\u00e9dico.\" width=\"699\" height=\"826\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-2.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-2-254x300.jpg 254w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-2-355x420.jpg 355w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-2-150x177.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-2-300x355.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-2-696x822.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-144477\" class=\"wp-caption-text\">Ante la imposibilidad de salir en su veh\u00edculo, Carolina \u00c1lvarez debi\u00f3 trasladarse en bus a Santiago para no perder su control m\u00e9dico.<\/figcaption><\/figure>\n<figure id=\"attachment_144478\" aria-describedby=\"caption-attachment-144478\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-144478\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-3.jpg\" alt=\"Pese a las dificultades, la vecina logr\u00f3 llegar \u2013aunque con retraso- a su control m\u00e9dico en Santiago, donde finalmente fue atendida.\" width=\"699\" height=\"1038\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-3.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-3-202x300.jpg 202w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-3-690x1024.jpg 690w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-3-283x420.jpg 283w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-3-150x223.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-3-300x445.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-3-696x1034.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-144478\" class=\"wp-caption-text\">Pese a las dificultades, la vecina logr\u00f3 llegar \u2013aunque con retraso- a su control m\u00e9dico en Santiago, donde finalmente fue atendida.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El veh\u00edculo permaneci\u00f3 m\u00e1s de ocho horas frente a su domicilio, pese a la intervenci\u00f3n de autoridades. Desde el municipio detallaron protocolos y anunciaron implementaci\u00f3n de sistema de retiro con gr\u00faa.- Una compleja situaci\u00f3n vivi\u00f3 la vecina del centro de San Felipe, Carolina \u00c1lvarez, luego que un veh\u00edculo estacionado frente a su domicilio le impidiera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":144475,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-144474","post","type-post","status-publish","format-standard","has-post-thumbnail","category-comunidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vecina denuncia reiteradas obstrucciones vehiculares en salida de su vivienda: Qued\u00f3 bloqueada y debi\u00f3 viajar en bus a control m\u00e9dico - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vecina denuncia reiteradas obstrucciones vehiculares en salida de su vivienda: Qued\u00f3 bloqueada y debi\u00f3 viajar en bus a control m\u00e9dico - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"El veh\u00edculo permaneci\u00f3 m\u00e1s de ocho horas frente a su domicilio, pese a la intervenci\u00f3n de autoridades. Desde el municipio detallaron protocolos y anunciaron implementaci\u00f3n de sistema de retiro con gr\u00faa.- Una compleja situaci\u00f3n vivi\u00f3 la vecina del centro de San Felipe, Carolina \u00c1lvarez, luego que un veh\u00edculo estacionado frente a su domicilio le impidiera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T00:58:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-1-copia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"344\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Vecina denuncia reiteradas obstrucciones vehiculares en salida de su vivienda: Qued\u00f3 bloqueada y debi\u00f3 viajar en bus a control m\u00e9dico\",\"datePublished\":\"2026-05-07T00:58:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\\\/\"},\"wordCount\":1092,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/denuncia-obstruccion-vehicular-1-copia.jpg\",\"articleSection\":[\"Comunidad\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\\\/\",\"name\":\"Vecina denuncia reiteradas obstrucciones vehiculares en salida de su vivienda: Qued\u00f3 bloqueada y debi\u00f3 viajar en bus a control m\u00e9dico - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/denuncia-obstruccion-vehicular-1-copia.jpg\",\"datePublished\":\"2026-05-07T00:58:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/denuncia-obstruccion-vehicular-1-copia.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/denuncia-obstruccion-vehicular-1-copia.jpg\",\"width\":700,\"height\":344},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vecina denuncia reiteradas obstrucciones vehiculares en salida de su vivienda: Qued\u00f3 bloqueada y debi\u00f3 viajar en bus a control m\u00e9dico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vecina denuncia reiteradas obstrucciones vehiculares en salida de su vivienda: Qued\u00f3 bloqueada y debi\u00f3 viajar en bus a control m\u00e9dico - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/","og_locale":"es_ES","og_type":"article","og_title":"Vecina denuncia reiteradas obstrucciones vehiculares en salida de su vivienda: Qued\u00f3 bloqueada y debi\u00f3 viajar en bus a control m\u00e9dico - Diario El Trabajo","og_description":"El veh\u00edculo permaneci\u00f3 m\u00e1s de ocho horas frente a su domicilio, pese a la intervenci\u00f3n de autoridades. Desde el municipio detallaron protocolos y anunciaron implementaci\u00f3n de sistema de retiro con gr\u00faa.- Una compleja situaci\u00f3n vivi\u00f3 la vecina del centro de San Felipe, Carolina \u00c1lvarez, luego que un veh\u00edculo estacionado frente a su domicilio le impidiera [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2026-05-07T00:58:45+00:00","og_image":[{"width":700,"height":344,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-1-copia.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Vecina denuncia reiteradas obstrucciones vehiculares en salida de su vivienda: Qued\u00f3 bloqueada y debi\u00f3 viajar en bus a control m\u00e9dico","datePublished":"2026-05-07T00:58:45+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/"},"wordCount":1092,"commentCount":0,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-1-copia.jpg","articleSection":["Comunidad"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/","url":"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/","name":"Vecina denuncia reiteradas obstrucciones vehiculares en salida de su vivienda: Qued\u00f3 bloqueada y debi\u00f3 viajar en bus a control m\u00e9dico - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-1-copia.jpg","datePublished":"2026-05-07T00:58:45+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-1-copia.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/denuncia-obstruccion-vehicular-1-copia.jpg","width":700,"height":344},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/vecina-denuncia-reiteradas-obstrucciones-vehiculares-en-salida-de-su-vivienda-quedo-bloqueada-y-debio-viajar-en-bus-a-control-medico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Vecina denuncia reiteradas obstrucciones vehiculares en salida de su vivienda: Qued\u00f3 bloqueada y debi\u00f3 viajar en bus a control m\u00e9dico"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/144474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=144474"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/144474\/revisions"}],"predecessor-version":[{"id":144480,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/144474\/revisions\/144480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/144475"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=144474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=144474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=144474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}