{"id":144604,"date":"2026-05-12T21:43:09","date_gmt":"2026-05-13T00:43:09","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=144604"},"modified":"2026-05-12T21:43:09","modified_gmt":"2026-05-13T00:43:09","slug":"hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/","title":{"rendered":"Hosla presenta modelo de atenci\u00f3n para ni\u00f1os TEA en Unidad de Emergencia Pedi\u00e1trica"},"content":{"rendered":"<ul>\n<li><strong>Iniciativa se transform\u00f3 en pionera en todo Aconcagua.\u2013<\/strong><\/li>\n<\/ul>\n<p>Un verdadero hito para la red p\u00fablica de salud de la regi\u00f3n, signific\u00f3 la puesta en marcha del modelo de atenci\u00f3n para ni\u00f1os, ni\u00f1as y adolescentes TEA en la Unidad de Emergencia Pedi\u00e1trica del Hospital San Juan de Dios de Los Andes.<\/p>\n<p>El nuevo modelo permite que, tras presentar el carnet de discapacidad al ingresar por cualquier emergencia m\u00e9dica, y a pesar de ser categorizados, estos pacientes son ingresados de inmediato a una sala de atenci\u00f3n especialmente acondicionada para ellos.<\/p>\n<p>La directora del Hospital de Los Andes, <strong>Ana Lazcano<\/strong>, se\u00f1al\u00f3 que se trata de un modelo de atenci\u00f3n que dignifica y humaniza la atenci\u00f3n a los ni\u00f1os, ni\u00f1as y adolescentes y sus familias, brindando contenci\u00f3n, empat\u00eda, claridad y un espacio seguro.<\/p>\n<p>\u00ab<em>Ac\u00e1 este hito contribuye a una mejor atenci\u00f3n, una atenci\u00f3n m\u00e1s oportuna, de calidad, y por sobre todo, m\u00e1s humanizada para los ni\u00f1os y ni\u00f1as en esta condici\u00f3n, y tambi\u00e9n para sus familias<\/em> (\u2026) <em>Orgullosamente, decimos que somos los primeros en la red de Aconcagua que tenemos este tipo de atenci\u00f3n, y queremos compartir este proceso con toda aquella instituci\u00f3n en salud p\u00fablica y privada que lo quieran acoger\u00bb<\/em>, indic\u00f3.<\/p>\n<p>El modelo de atenci\u00f3n \u2018Espacios que Calman\u2019 y la sala de atenci\u00f3n denominada \u2018SER\u2019, surgieron de un diplomado en humanizaci\u00f3n realizado por funcionarias de diferentes servicios y unidades del Hosla, en la Universidad de Valpara\u00edso (UV).<\/p>\n<p>Para ello contaron con apoyo transversal del establecimiento, desde la Direcci\u00f3n, hasta unidades operativas que apoyaron en la ejecuci\u00f3n de un proyecto que comprometi\u00f3 voluntades e inter\u00e9s por buscar una soluci\u00f3n inclusiva a cientos de familias en momentos dif\u00edciles, como cuando un ni\u00f1o, ni\u00f1a o adolescente TEA sufre una emergencia m\u00e9dica. As\u00ed lo explic\u00f3 una de las gestoras de la iniciativa y supervisora de la Unidad de Emergencia Hospitalaria, enfermera <strong>Loreto Abarca<\/strong>.<\/p>\n<p>\u00ab<em>Este proyecto surgi\u00f3 de un grupo de profesionales de la unidad de la emergencia, somos de distintos servicios, en conjunto con la Universidad de Valpara\u00edso creamos un proyecto de trato humanizado en la unidad de emergencia para los ni\u00f1os TEA. Va a generar un cambio en la modalidad de atenci\u00f3n en nuestra unidad, en donde vamos a utilizar herramientas que existen a nivel internacional, para comunicarnos y dejar que estos ni\u00f1os sean invisibles en la atenci\u00f3n\u00bb<\/em>, sostuvo<\/p>\n<p>El modelo de atenci\u00f3n considera que todas las atenciones a los pacientes TEA se realicen en la Sala SER, raz\u00f3n por la cual son los profesionales cl\u00ednicos quienes se trasladan a dicha dependencia. Adem\u00e1s, los pediatras, enfermeros y Tens est\u00e1n capacitados en el uso de pictogramas que facilitan la comunicaci\u00f3n con los pacientes.<\/p>\n<p>Cabe se\u00f1alar que en la materializaci\u00f3n del proyecto, las alumnas del diplomado tuvieron la colaboraci\u00f3n t\u00e9cnica de la agrupaci\u00f3n TEAdmiramos de Los Andes y su ejecuci\u00f3n tuvo un costo cercano a los $500.000, inversi\u00f3n muy baja, pero que tiene un alto y positivo impacto en los usuarios.<\/p>\n<p>Por este motivo, tanto sus gestoras, como las autoridades e invitados en la presentaci\u00f3n del mismo, compartieron la opini\u00f3n que es replicable en otros establecimientos de salud p\u00fablicos y privados.<\/p>\n<figure id=\"attachment_144605\" aria-describedby=\"caption-attachment-144605\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-144605\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-1.jpg\" alt=\"Equipo de profesionales gener\u00f3 esta pionera iniciativa. \" width=\"699\" height=\"391\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-1.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-1-300x168.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-1-150x84.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-1-696x389.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-144605\" class=\"wp-caption-text\">Equipo de profesionales gener\u00f3 esta pionera iniciativa.<\/figcaption><\/figure>\n<figure id=\"attachment_144607\" aria-describedby=\"caption-attachment-144607\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-144607\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-3.jpg\" alt=\"Proyecto es pionero en Aconcagua. \" width=\"699\" height=\"419\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-3.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-3-300x180.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-3-150x90.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-3-696x417.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-144607\" class=\"wp-caption-text\">Proyecto es pionero en Aconcagua.<\/figcaption><\/figure>\n<figure id=\"attachment_144606\" aria-describedby=\"caption-attachment-144606\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-144606\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-2.jpg\" alt=\"Estas son parte de las medidas adoptadas\" width=\"699\" height=\"454\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-2.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-2-300x195.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-2-647x420.jpg 647w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-2-150x97.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-2-696x452.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-144606\" class=\"wp-caption-text\">Estas son parte de las medidas adoptadas<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Iniciativa se transform\u00f3 en pionera en todo Aconcagua.\u2013 Un verdadero hito para la red p\u00fablica de salud de la regi\u00f3n, signific\u00f3 la puesta en marcha del modelo de atenci\u00f3n para ni\u00f1os, ni\u00f1as y adolescentes TEA en la Unidad de Emergencia Pedi\u00e1trica del Hospital San Juan de Dios de Los Andes. El nuevo modelo permite que, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":144607,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-144604","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cronica-2"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hosla presenta modelo de atenci\u00f3n para ni\u00f1os TEA en Unidad de Emergencia Pedi\u00e1trica - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hosla presenta modelo de atenci\u00f3n para ni\u00f1os TEA en Unidad de Emergencia Pedi\u00e1trica - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Iniciativa se transform\u00f3 en pionera en todo Aconcagua.\u2013 Un verdadero hito para la red p\u00fablica de salud de la regi\u00f3n, signific\u00f3 la puesta en marcha del modelo de atenci\u00f3n para ni\u00f1os, ni\u00f1as y adolescentes TEA en la Unidad de Emergencia Pedi\u00e1trica del Hospital San Juan de Dios de Los Andes. El nuevo modelo permite que, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T00:43:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"699\" \/>\n\t<meta property=\"og:image:height\" content=\"419\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Hosla presenta modelo de atenci\u00f3n para ni\u00f1os TEA en Unidad de Emergencia Pedi\u00e1trica\",\"datePublished\":\"2026-05-13T00:43:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\\\/\"},\"wordCount\":627,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/atencion-TEA-en-Hosla-3.jpg\",\"articleSection\":[\"Cr\u00f3nica\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\\\/\",\"name\":\"Hosla presenta modelo de atenci\u00f3n para ni\u00f1os TEA en Unidad de Emergencia Pedi\u00e1trica - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/atencion-TEA-en-Hosla-3.jpg\",\"datePublished\":\"2026-05-13T00:43:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/atencion-TEA-en-Hosla-3.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/atencion-TEA-en-Hosla-3.jpg\",\"width\":699,\"height\":419,\"caption\":\"Proyecto es pionero en Aconcagua.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hosla presenta modelo de atenci\u00f3n para ni\u00f1os TEA en Unidad de Emergencia Pedi\u00e1trica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hosla presenta modelo de atenci\u00f3n para ni\u00f1os TEA en Unidad de Emergencia Pedi\u00e1trica - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/","og_locale":"es_ES","og_type":"article","og_title":"Hosla presenta modelo de atenci\u00f3n para ni\u00f1os TEA en Unidad de Emergencia Pedi\u00e1trica - Diario El Trabajo","og_description":"Iniciativa se transform\u00f3 en pionera en todo Aconcagua.\u2013 Un verdadero hito para la red p\u00fablica de salud de la regi\u00f3n, signific\u00f3 la puesta en marcha del modelo de atenci\u00f3n para ni\u00f1os, ni\u00f1as y adolescentes TEA en la Unidad de Emergencia Pedi\u00e1trica del Hospital San Juan de Dios de Los Andes. El nuevo modelo permite que, [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2026-05-13T00:43:09+00:00","og_image":[{"width":699,"height":419,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-3.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Hosla presenta modelo de atenci\u00f3n para ni\u00f1os TEA en Unidad de Emergencia Pedi\u00e1trica","datePublished":"2026-05-13T00:43:09+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/"},"wordCount":627,"commentCount":0,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-3.jpg","articleSection":["Cr\u00f3nica"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/","url":"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/","name":"Hosla presenta modelo de atenci\u00f3n para ni\u00f1os TEA en Unidad de Emergencia Pedi\u00e1trica - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-3.jpg","datePublished":"2026-05-13T00:43:09+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-3.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/05\/atencion-TEA-en-Hosla-3.jpg","width":699,"height":419,"caption":"Proyecto es pionero en Aconcagua."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/hosla-presenta-modelo-de-atencion-para-ninos-tea-en-unidad-de-emergencia-pediatrica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Hosla presenta modelo de atenci\u00f3n para ni\u00f1os TEA en Unidad de Emergencia Pedi\u00e1trica"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/144604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=144604"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/144604\/revisions"}],"predecessor-version":[{"id":144608,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/144604\/revisions\/144608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/144607"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=144604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=144604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=144604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}