{"id":145867,"date":"2026-07-14T21:37:45","date_gmt":"2026-07-15T00:37:45","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=145867"},"modified":"2026-07-14T21:37:45","modified_gmt":"2026-07-15T00:37:45","slug":"detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/","title":{"rendered":"Detienen a dos personas por posesi\u00f3n de armas y municiones en Paso Los Libertadores"},"content":{"rendered":"<ul>\n<li><strong>Elementos fueron encontrados tras fiscalizaciones de personal de Aduanas y Carabineros.\u2013<\/strong><\/li>\n<\/ul>\n<p>En dos operativos independientes realizados en el Complejo Fronterizo Los Libertadores, personal del Servicio Nacional de Aduanas junto a Carabineros interceptaron y detuvieron a dos personas que intentaban ingresar armamentos de fuego y municiones al territorio nacional de forma ilegal.<\/p>\n<p>El primer procedimiento se gest\u00f3 durante la revisi\u00f3n de un autob\u00fas de transporte de pasajeros proveniente de Mendoza con destino a Santiago. Al fiscalizar a uno de los pasajeros, identificado como <strong>H<\/strong>.<strong>A<\/strong>.<strong>G<\/strong>., de 58 a\u00f1os de edad, los funcionarios descubrieron que llevaba elementos adosados a su abdomen mediante una faja.<\/p>\n<p>Tras una inspecci\u00f3n minuciosa, se incautaron dos pistolas marca Glock (modelos 17 y 45, calibre 9 mm) que ten\u00edan sus n\u00fameros de serie borrados. Adem\u00e1s, el imputado transportaba tres cargadores con capacidad para 17 tiros, un cargador r\u00e1pido y accesorios de empu\u00f1adura.<\/p>\n<p>El segundo hecho afect\u00f3 a un autom\u00f3vil particular que viajaba desde C\u00f3rdoba con destino a la comuna de Los Andes. Durante el control, el personal procedi\u00f3 a la revisi\u00f3n del conductor, un ciudadano de 53 a\u00f1os de edad identificado con las iniciales <strong>J<\/strong>.<strong>A<\/strong>.<strong>O<\/strong>.<\/p>\n<p>Al registrar el veh\u00edculo, los funcionarios descubrieron una pistola marca Bersa, modelo Thunder 9, calibre 9 mm, la cual se encontraba desarmada y oculta en distintos compartimentos del m\u00f3vil. Junto al arma, se hall\u00f3 un cargador y un total de 18 municiones calibre 9 mm sin percutar.<\/p>\n<p>Al respecto, el capit\u00e1n <strong>Jos\u00e9 Miguel V\u00e1squez S\u00e1nchez<\/strong>, subcomisario de la Subcomisar\u00eda Los Libertadores, se\u00f1al\u00f3 que <em>\u00abel d\u00eda de ayer<\/em> (lunes)<em>, a ra\u00edz de los diversos controles exhaustivos que se realizan en el Complejo Fronterizo Los Libertadores, se detuvieron a dos ciudadanos de nacionalidad argentina quienes manten\u00edan posesi\u00f3n de armas de fuego y munici\u00f3n<\/em>.<\/p>\n<p>\u00ab<em>Esto por parte de las acciones realizadas en el complejo fronterizo, espec\u00edficamente, por personal del Servicio Nacional de Aduanas, quien, conjuntamente con Carabineros, adoptaron dicho procedimiento\u00bb<\/em>, agreg\u00f3.<\/p>\n<p>En este contexto, el capit\u00e1n V\u00e1squez detall\u00f3 que <em>\u00abeste procedimiento se gest\u00f3, en primera instancia con una persona que oculta a trav\u00e9s de una faja adosada a su cuerpo, manten\u00eda dos pistoladas<\/em> (\u2026) <em>con la finalidad de ocultar y pasar estos dos armamentos con sus respectivos cargadores desde Argentina hacia Chile\u00bb<\/em>.<\/p>\n<p>Del mismo modo, el subcomisario de Los Libertadores, indic\u00f3 que <em>\u00abesto fue detectado en bus que proven\u00eda de Mendoza y ten\u00eda destino Santiago, por lo cual se dio cuenta al Ministerio P\u00fablico quien dispuso diversas diligencias investigativas y que esta persona pasara a control de detenci\u00f3n\u00bb<\/em>, estableci\u00f3.<\/p>\n<p>Junto con esto, V\u00e1squez sostuvo que <em>\u00abasimismo, posteriormente, en horas de la tarde, se gest\u00f3 un segundo procedimiento donde un ciudadano argentino en su veh\u00edculo particular ingres\u00f3 en su autom\u00f3vil desde la ciudad de C\u00f3rdoba con destino a la ciudad de Los Andes, donde al efectuar el control y revisi\u00f3n, personal de Aduanas detect\u00f3 que se encontraba una pistola, desarmada, con sus diversas partes ocultas en diversos compartimentos del veh\u00edculo\u00bb<\/em>.<\/p>\n<p>Finalmente, el encargado de la Subcomisar\u00eda Los Libertadores coment\u00f3 que <em>\u00ablo anterior, se gesta en un trabajo interinstitucional para detectar delitos transnacionales que se puedan cometer tanto en el ingreso hacia Chile como en la salida a Argentina\u00bb<\/em>, concluy\u00f3.<\/p>\n<p>Ambas causas quedaron a disposici\u00f3n de la Fiscal\u00eda, que instruy\u00f3 el trabajo conjunto de las instituciones fiscalizadoras para el levantamiento de la evidencia.<\/p>\n<figure id=\"attachment_145868\" aria-describedby=\"caption-attachment-145868\" style=\"width: 698px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-145868\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-1.jpg\" alt=\"Arma y municiones se decomisaron en el segundo operativo. \" width=\"698\" height=\"577\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-1.jpg 698w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-1-300x248.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-1-508x420.jpg 508w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-1-150x124.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-1-696x575.jpg 696w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><figcaption id=\"caption-attachment-145868\" class=\"wp-caption-text\">Arma y municiones se decomisaron en el segundo operativo.<\/figcaption><\/figure>\n<figure id=\"attachment_145869\" aria-describedby=\"caption-attachment-145869\" style=\"width: 699px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-145869\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-2.jpg\" alt=\"Esta es el arma incautada en el primer procedimiento. \" width=\"699\" height=\"640\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-2.jpg 699w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-2-300x275.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-2-459x420.jpg 459w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-2-150x137.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-2-696x637.jpg 696w\" sizes=\"auto, (max-width: 699px) 100vw, 699px\" \/><figcaption id=\"caption-attachment-145869\" class=\"wp-caption-text\">Esta es el arma incautada en el primer procedimiento.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Elementos fueron encontrados tras fiscalizaciones de personal de Aduanas y Carabineros.\u2013 En dos operativos independientes realizados en el Complejo Fronterizo Los Libertadores, personal del Servicio Nacional de Aduanas junto a Carabineros interceptaron y detuvieron a dos personas que intentaban ingresar armamentos de fuego y municiones al territorio nacional de forma ilegal. El primer procedimiento se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":145868,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-145867","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Detienen a dos personas por posesi\u00f3n de armas y municiones en Paso Los Libertadores - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detienen a dos personas por posesi\u00f3n de armas y municiones en Paso Los Libertadores - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Elementos fueron encontrados tras fiscalizaciones de personal de Aduanas y Carabineros.\u2013 En dos operativos independientes realizados en el Complejo Fronterizo Los Libertadores, personal del Servicio Nacional de Aduanas junto a Carabineros interceptaron y detuvieron a dos personas que intentaban ingresar armamentos de fuego y municiones al territorio nacional de forma ilegal. El primer procedimiento se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T00:37:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"698\" \/>\n\t<meta property=\"og:image:height\" content=\"577\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Detienen a dos personas por posesi\u00f3n de armas y municiones en Paso Los Libertadores\",\"datePublished\":\"2026-07-15T00:37:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\\\/\"},\"wordCount\":627,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/detenidos-1.jpg\",\"articleSection\":[\"Policial\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\\\/\",\"name\":\"Detienen a dos personas por posesi\u00f3n de armas y municiones en Paso Los Libertadores - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/detenidos-1.jpg\",\"datePublished\":\"2026-07-15T00:37:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/detenidos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/detenidos-1.jpg\",\"width\":698,\"height\":577,\"caption\":\"Arma y municiones se decomisaron en el segundo operativo.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detienen a dos personas por posesi\u00f3n de armas y municiones en Paso Los Libertadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detienen a dos personas por posesi\u00f3n de armas y municiones en Paso Los Libertadores - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/","og_locale":"es_ES","og_type":"article","og_title":"Detienen a dos personas por posesi\u00f3n de armas y municiones en Paso Los Libertadores - Diario El Trabajo","og_description":"Elementos fueron encontrados tras fiscalizaciones de personal de Aduanas y Carabineros.\u2013 En dos operativos independientes realizados en el Complejo Fronterizo Los Libertadores, personal del Servicio Nacional de Aduanas junto a Carabineros interceptaron y detuvieron a dos personas que intentaban ingresar armamentos de fuego y municiones al territorio nacional de forma ilegal. El primer procedimiento se [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2026-07-15T00:37:45+00:00","og_image":[{"width":698,"height":577,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-1.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Detienen a dos personas por posesi\u00f3n de armas y municiones en Paso Los Libertadores","datePublished":"2026-07-15T00:37:45+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/"},"wordCount":627,"commentCount":0,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-1.jpg","articleSection":["Policial"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/","url":"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/","name":"Detienen a dos personas por posesi\u00f3n de armas y municiones en Paso Los Libertadores - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-1.jpg","datePublished":"2026-07-15T00:37:45+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-1.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/detenidos-1.jpg","width":698,"height":577,"caption":"Arma y municiones se decomisaron en el segundo operativo."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/detienen-a-dos-personas-por-posesion-de-armas-y-municiones-en-paso-los-libertadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Detienen a dos personas por posesi\u00f3n de armas y municiones en Paso Los Libertadores"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/145867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=145867"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/145867\/revisions"}],"predecessor-version":[{"id":145870,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/145867\/revisions\/145870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/145868"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=145867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=145867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=145867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}