{"id":145874,"date":"2026-07-14T21:39:53","date_gmt":"2026-07-15T00:39:53","guid":{"rendered":"https:\/\/eltrabajo.cl\/web\/?p=145874"},"modified":"2026-07-14T21:39:53","modified_gmt":"2026-07-15T00:39:53","slug":"rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision","status":"publish","type":"post","link":"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/","title":{"rendered":"Rechazan recurso de nulidad a ex funcionario municipal y deber\u00e1 cumplir condena en prisi\u00f3n"},"content":{"rendered":"<p><span style=\"color: #ff0000;\">Delitos de cohecho:<\/span><\/p>\n<ul>\n<li><strong>El ex dirigente sindical adem\u00e1s qued\u00f3 inhabilitado para ejercer cargos en el sector p\u00fablico.\u2013<\/strong><\/li>\n<\/ul>\n<p>La Corte de Apelaciones de Valpara\u00edso rechaz\u00f3 el recurso de nulidad presentado por la defensa del ex funcionario municipal y ex presidente de la ASEMUCH de San Felipe, <strong>Marcelo Mazuela Henr\u00edquez<\/strong>, tras ser condenado a la pena de 5 a\u00f1os y 1 d\u00eda de prisi\u00f3n, adem\u00e1s de la multa de un mill\u00f3n de pesos y la inhabilitaci\u00f3n de una d\u00e9cada para ejercer cargos p\u00fablicos; todo esto, por dos delitos de cohecho.<\/p>\n<p>El extrabajador de la entidad edilicia, se desempe\u00f1aba como encargado del Dep\u00f3sito Municipal, momento en el que acept\u00f3 dinero para el retiro de dos veh\u00edculos. Dichos recursos, eran directamente para su beneficio. El hecho fue denunciado por la actual administraci\u00f3n municipal, quienes valoraron la ratificaci\u00f3n de la condena.<\/p>\n<p>En este contexto, desde el municipio se\u00f1alaron que <em>\u00abesta resoluci\u00f3n reafirma una forma de entender el servicio p\u00fablico. Cuando existen antecedentes de eventuales irregularidades que puedan comprometer la probidad, el patrimonio municipal o la confianza de la comunidad, corresponde actuar con responsabilidad, ejercer las acciones que la ley contempla y colaborar con las instituciones llamadas a investigar y determinar las responsabilidades que correspondan\u00bb<\/em>.<\/p>\n<p>Asimismo, agregaron que <em>\u00abparalelamente, el municipio adopt\u00f3 medidas destinadas a fortalecer los mecanismos de control y enfrentar las consecuencias operativas derivadas de lo ocurrido en el Dep\u00f3sito Municipal\u00bb<\/em>, aseguraron.<\/p>\n<p>Por su parte, la alcaldesa de San Felipe, <strong>Carmen Castillo<\/strong>, coment\u00f3 que <em>\u00abla transparencia y la probidad no pueden quedarse solo en declaraciones, se demuestran en la manera que actuamos cuando advertimos que algo no est\u00e1 bien. Este es un hecho que tambi\u00e9n nos duele, porque nunca es sencillo enfrentar una situaci\u00f3n que involucra a quien ha formado parte de nuestra instituci\u00f3n\u00bb<\/em>.<\/p>\n<p>Del mismo modo, la edil a\u00f1adi\u00f3 que <em>\u00aba\u00fan as\u00ed, nuestra responsabilidad es no mirar hacia al lado, adoptar las medidas que corresponda y procurar siempre hacer lo correcto. Cuando existen antecedentes de una irregularidad es nuestro deber denunciarlo, colaborar con la justicia y revisar nuestros propios procedimientos para evitar que hechos similares vuelvan a ocurrir\u00bb<\/em>, coment\u00f3 la jefa comunal.<\/p>\n<p>Finamente, Castillo expres\u00f3 que <em>\u00abese es el criterio que ha guiado a esta administraci\u00f3n y que seguiremos fortaleciendo, porque los recursos p\u00fablicos pertenecen a toda la comunidad y deben de ser resguardados con responsabilidad\u00bb<\/em>, cerr\u00f3.<\/p>\n<figure id=\"attachment_145875\" aria-describedby=\"caption-attachment-145875\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-145875\" src=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/Marcelo-Mazuela.jpg\" alt=\"Corte de Apelaciones rechaz\u00f3 recurso de nulidad de ex funcionario municipal. \" width=\"700\" height=\"582\" srcset=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/Marcelo-Mazuela.jpg 700w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/Marcelo-Mazuela-300x249.jpg 300w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/Marcelo-Mazuela-505x420.jpg 505w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/Marcelo-Mazuela-150x125.jpg 150w, https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/Marcelo-Mazuela-696x579.jpg 696w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-145875\" class=\"wp-caption-text\">Corte de Apelaciones rechaz\u00f3 recurso de nulidad de ex funcionario municipal.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Delitos de cohecho: El ex dirigente sindical adem\u00e1s qued\u00f3 inhabilitado para ejercer cargos en el sector p\u00fablico.\u2013 La Corte de Apelaciones de Valpara\u00edso rechaz\u00f3 el recurso de nulidad presentado por la defensa del ex funcionario municipal y ex presidente de la ASEMUCH de San Felipe, Marcelo Mazuela Henr\u00edquez, tras ser condenado a la pena de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":145875,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-145874","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tribunales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rechazan recurso de nulidad a ex funcionario municipal y deber\u00e1 cumplir condena en prisi\u00f3n - Diario El Trabajo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rechazan recurso de nulidad a ex funcionario municipal y deber\u00e1 cumplir condena en prisi\u00f3n - Diario El Trabajo\" \/>\n<meta property=\"og:description\" content=\"Delitos de cohecho: El ex dirigente sindical adem\u00e1s qued\u00f3 inhabilitado para ejercer cargos en el sector p\u00fablico.\u2013 La Corte de Apelaciones de Valpara\u00edso rechaz\u00f3 el recurso de nulidad presentado por la defensa del ex funcionario municipal y ex presidente de la ASEMUCH de San Felipe, Marcelo Mazuela Henr\u00edquez, tras ser condenado a la pena de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario El Trabajo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElTrabajoDiario\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T00:39:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/Marcelo-Mazuela.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"582\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diario El Trabajo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:site\" content=\"@diarioeltrabajo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diario El Trabajo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\\\/\"},\"author\":{\"name\":\"Diario El Trabajo\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\"},\"headline\":\"Rechazan recurso de nulidad a ex funcionario municipal y deber\u00e1 cumplir condena en prisi\u00f3n\",\"datePublished\":\"2026-07-15T00:39:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\\\/\"},\"wordCount\":443,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Marcelo-Mazuela.jpg\",\"articleSection\":[\"Tribunales\"],\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\\\/\",\"name\":\"Rechazan recurso de nulidad a ex funcionario municipal y deber\u00e1 cumplir condena en prisi\u00f3n - Diario El Trabajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Marcelo-Mazuela.jpg\",\"datePublished\":\"2026-07-15T00:39:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Marcelo-Mazuela.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Marcelo-Mazuela.jpg\",\"width\":700,\"height\":582,\"caption\":\"Corte de Apelaciones rechaz\u00f3 recurso de nulidad de ex funcionario municipal.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rechazan recurso de nulidad a ex funcionario municipal y deber\u00e1 cumplir condena en prisi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"name\":\"Diario El Trabajo\",\"description\":\"Desde 1929 construyendo Identidad Local\",\"publisher\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#organization\",\"name\":\"Diario El Trabajo\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"contentUrl\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/profile-image-ig-page-diarioeltrabajo.jpg\",\"width\":823,\"height\":823,\"caption\":\"Diario El Trabajo\"},\"image\":{\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElTrabajoDiario\",\"https:\\\/\\\/x.com\\\/diarioeltrabajo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/#\\\/schema\\\/person\\\/45efd3d17f86ec456e44dd7debe1bf19\",\"name\":\"Diario El Trabajo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g\",\"caption\":\"Diario El Trabajo\"},\"sameAs\":[\"https:\\\/\\\/eltrabajo.cl\\\/web\"],\"url\":\"https:\\\/\\\/eltrabajo.cl\\\/web\\\/author\\\/diario-el-trabajo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rechazan recurso de nulidad a ex funcionario municipal y deber\u00e1 cumplir condena en prisi\u00f3n - Diario El Trabajo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/","og_locale":"es_ES","og_type":"article","og_title":"Rechazan recurso de nulidad a ex funcionario municipal y deber\u00e1 cumplir condena en prisi\u00f3n - Diario El Trabajo","og_description":"Delitos de cohecho: El ex dirigente sindical adem\u00e1s qued\u00f3 inhabilitado para ejercer cargos en el sector p\u00fablico.\u2013 La Corte de Apelaciones de Valpara\u00edso rechaz\u00f3 el recurso de nulidad presentado por la defensa del ex funcionario municipal y ex presidente de la ASEMUCH de San Felipe, Marcelo Mazuela Henr\u00edquez, tras ser condenado a la pena de [&hellip;]","og_url":"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/","og_site_name":"Diario El Trabajo","article_publisher":"https:\/\/www.facebook.com\/ElTrabajoDiario","article_published_time":"2026-07-15T00:39:53+00:00","og_image":[{"width":700,"height":582,"url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/Marcelo-Mazuela.jpg","type":"image\/jpeg"}],"author":"Diario El Trabajo","twitter_card":"summary_large_image","twitter_creator":"@diarioeltrabajo","twitter_site":"@diarioeltrabajo","twitter_misc":{"Escrito por":"Diario El Trabajo","Tiempo estimado de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/#article","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/"},"author":{"name":"Diario El Trabajo","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19"},"headline":"Rechazan recurso de nulidad a ex funcionario municipal y deber\u00e1 cumplir condena en prisi\u00f3n","datePublished":"2026-07-15T00:39:53+00:00","mainEntityOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/"},"wordCount":443,"commentCount":0,"publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/Marcelo-Mazuela.jpg","articleSection":["Tribunales"],"inLanguage":"es-CL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/","url":"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/","name":"Rechazan recurso de nulidad a ex funcionario municipal y deber\u00e1 cumplir condena en prisi\u00f3n - Diario El Trabajo","isPartOf":{"@id":"https:\/\/eltrabajo.cl\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/#primaryimage"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/#primaryimage"},"thumbnailUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/Marcelo-Mazuela.jpg","datePublished":"2026-07-15T00:39:53+00:00","breadcrumb":{"@id":"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/#primaryimage","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/Marcelo-Mazuela.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2026\/07\/Marcelo-Mazuela.jpg","width":700,"height":582,"caption":"Corte de Apelaciones rechaz\u00f3 recurso de nulidad de ex funcionario municipal."},{"@type":"BreadcrumbList","@id":"https:\/\/eltrabajo.cl\/web\/rechazan-recurso-de-nulidad-a-ex-funcionario-municipal-y-debera-cumplir-condena-en-prision\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eltrabajo.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Rechazan recurso de nulidad a ex funcionario municipal y deber\u00e1 cumplir condena en prisi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/eltrabajo.cl\/web\/#website","url":"https:\/\/eltrabajo.cl\/web\/","name":"Diario El Trabajo","description":"Desde 1929 construyendo Identidad Local","publisher":{"@id":"https:\/\/eltrabajo.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eltrabajo.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/eltrabajo.cl\/web\/#organization","name":"Diario El Trabajo","url":"https:\/\/eltrabajo.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","contentUrl":"https:\/\/eltrabajo.cl\/web\/wp-content\/uploads\/2024\/06\/profile-image-ig-page-diarioeltrabajo.jpg","width":823,"height":823,"caption":"Diario El Trabajo"},"image":{"@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElTrabajoDiario","https:\/\/x.com\/diarioeltrabajo"]},{"@type":"Person","@id":"https:\/\/eltrabajo.cl\/web\/#\/schema\/person\/45efd3d17f86ec456e44dd7debe1bf19","name":"Diario El Trabajo","image":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e6ec277dc4aea2677c2dc301d4227957219329c985ab69a3efc12518b5161aa?s=96&d=mm&r=g","caption":"Diario El Trabajo"},"sameAs":["https:\/\/eltrabajo.cl\/web"],"url":"https:\/\/eltrabajo.cl\/web\/author\/diario-el-trabajo\/"}]}},"_links":{"self":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/145874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/comments?post=145874"}],"version-history":[{"count":1,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/145874\/revisions"}],"predecessor-version":[{"id":145876,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/posts\/145874\/revisions\/145876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media\/145875"}],"wp:attachment":[{"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/media?parent=145874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/categories?post=145874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eltrabajo.cl\/web\/wp-json\/wp\/v2\/tags?post=145874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}